{"id":79644,"date":"2023-04-03T14:46:35","date_gmt":"2023-04-03T14:46:35","guid":{"rendered":"https:\/\/www.granapadano.it\/recipe\/vellutata-di-ceci-castagne-e-salsiccia-con-rosmarino-e-grana-padano-dop-riserva-copy\/"},"modified":"2023-05-15T10:46:14","modified_gmt":"2023-05-15T10:46:14","slug":"ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva","status":"publish","type":"recipe","link":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/","title":{"rendered":"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/05\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-h-IMG_2371.jpg&#8221; title_text=&#8221;Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva&#8212;-m-IMG_2371&#8243; src_tablet=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/05\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-h-IMG_2371.jpg&#8221; src_phone=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/05\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-m-IMG_2371.jpg&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;single_recipe_content&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;13px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221;recipe_filter_section&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;|auto|-60px|auto|false|false&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||16px|||&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div>[\/et_pb_code][et_pb_code module_class=&#8221;recipe_likes_section&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"79644\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>13<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg&description=Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano Riserva<\/span><span class=\"tax_name\">Pasta<\/span><span class=\"tax_name\">Senza lattosio<\/span><\/div>[\/et_pb_code][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Merriweather||||||||&#8221; title_text_color=&#8221;#000000&#8243; title_font_size=&#8221;56px&#8221; title_font_size_tablet=&#8221;56px&#8221; title_font_size_phone=&#8221;36px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;recipe_display&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; min_height=&#8221;40px&#8221; custom_padding=&#8221;1px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Difficulty&#8221; _builder_version=&#8221;4.19.2&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZGlmZmljdWx0eSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxpbWcgc3JjPVwiL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDIyLzExL0dyb3VwLTM5My5zdmdcIj4iLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib2ZmIn19@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Persons&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfU2VydmVzIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiPGltZyBzcmM9XCIvd3AtY29udGVudC91cGxvYWRzLzIwMjIvMTEvR3JvdXAtMzgyLnN2Z1wiPiIsImFmdGVyIjoiIiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Duration&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZHVyYXRpb24iLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiJbdGltZV9pbWddIiwiYWZ0ZXIiOiIiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;ingredient_sec&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-6px|||||&#8221; custom_padding=&#8221;4px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;-19px|auto||auto||&#8221; custom_padding=&#8221;6px||0px|||&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Ingredienti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Ingredienti<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Ingredienti List&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;Merriweather||||||||&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;23px&#8221; header_4_line_height=&#8221;36px&#8221; width=&#8221;87%&#8221; custom_padding=&#8221;|30px||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>300 g di farina 00<br \/>\n3 uova<br \/>\n200 g di Grana Padano DOP Riserva<br \/>\n500 g di funghi<br \/>\n1 spicchio di aglio<br \/>\n1 cespo di radicchio<br \/>\n1 cipollotto<br \/>\nolio extravergine di oliva<br \/>\nsale<br \/>\npepe<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||-2px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Preparazione<\/h1>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 1<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||35px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Preparate la sfoglia dei ravioli disponendo la farina a fontana in una ciotola, al centro aggiungete le uova e iniziate a mescolare prima con l\u2019aiuto di una forchetta, poi impastate con le mani, fino a ottenere un impasto liscio e omogeneo.<br \/>\nCoprite l\u2019impasto ottenuto con la pellicola e fatelo riposare per mezz\u2019ora.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 2<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||35px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Nel frattempo preparate il ripieno: tagliate a pezzi i funghi fateli saltare in padella con un filo di olio extravergine di oliva e uno spicchio di aglio, fate cuocere per qualche minuto.<br \/>\nAggiustate di sale e pepe e frullateli in un mixer con Grana Padano Riserva grattugiato, fino a ottenere una purea.<br \/>\nDividete il panetto a met\u00e0 e tirate la sfoglia molto sottile realizzando due rettangoli uguali.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 3<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||35px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Riempite uno dei rettangoli con piccoli mucchietti di ripieno disponendoli in fila distanti circa 3 cm gli uni dagli altri, sovrapponete l\u2019altro rettangolo di sfoglia e realizzate i ravioli con una rotella taglia pasta.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]STEP 4[\/et_pb_text][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||35px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Fate cuocere i ravioli in abbondante acqua salata per 2-4 minuti, scolateli e fateli saltare a fuoco vivo in una padella antiaderente con un filo di olio, il cipollotto affettato e il radicchio tagliato a listeranno.<br \/>\nServite i ravioli con Grana Padano Riserva grattugiato e una macinata di pepe nero.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;related_product_wrapper ricette_main_sec&#8221; _builder_version=&#8221;4.20.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;97px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Ricette correlate<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;Code&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_main dev_main\"><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-al-brasato-e-grana-padano-riserva\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/03\/Ravioli-al-brasato-e-Grana-Padano-Riserva-p-IMG_4339.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Difficile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>270 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Ravioli al brasato e Grana Padano Riserva<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-con-farcitura-di-scampi-con-fonduta-di-grana-padano-erba-cipollina-e-scorza-darancia\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/03\/Ravioli-con-scampi-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Medio<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>105 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Ravioli con farcitura di scampi con fonduta di Grana Padano, erba cipollina e scorza d\u2019arancia<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-di-barbabietola-ripieni-di-ricotta-erbe-aromatiche-e-grana-padano-riserva\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/03\/Ravioli-di-barbabietola-ripieni-di-ricotta-erbe-aromatiche-e-Grana-Padano-Riserva-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Medio<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>60 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Ravioli di barbabietola ripieni di ricotta, erbe aromatiche e Grana Padano Riserva<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-di-ricotta-e-fave-e-grana-padano-riserva\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/03\/ravioli-di-ricotta-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Medio<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>120 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Ravioli di ricotta e fave e Grana Padano Riserva<\/h3><\/div><\/div><\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;scopri_btn&#8221; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;13px|auto||auto||&#8221; custom_padding=&#8221;||38px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;\/momenti-di-consumo\/&#8221; button_text=&#8221;SCOPRI TUTTE LE RICETTE&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;23px&#8221; button_text_color=&#8221;#0f0f0f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#221f1c&#8221; button_border_radius=&#8221;40px&#8221; button_font=&#8221;Merriweather|700|||||||&#8221; button_icon=&#8221;&#x35;||divi||400&#8243; button_icon_color=&#8221;#000000&#8243; button_on_hover=&#8221;off&#8221; custom_margin=&#8221;-1px|||||&#8221; custom_padding=&#8221;3px||3px|||&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#0f0f0f&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_icon_color__hover_enabled=&#8221;on|hover&#8221; button_icon_color__hover=&#8221;#FFFFFF&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div><div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"79644\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>13<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg&description=Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano Riserva<\/span><span class=\"tax_name\">Pasta<\/span><span class=\"tax_name\">Senza lattosio<\/span><\/div>Ingredienti300 g di farina 00 3 uova 200 g di Grana Padano DOP Riserva 500 g di funghi 1 spicchio di aglio 1 cespo di radicchio 1 cipollotto olio extravergine di oliva sale pepePreparazioneSTEP 1Preparate la sfoglia dei ravioli disponendo la farina a fontana in una ciotola, al centro aggiungete le uova e iniziate a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":98765,"menu_order":3079,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1920","footnotes":""},"recipe_cat":[3409],"stagionatura":[42],"variety":[43],"tempo":[54],"intolerance":[2968],"class_list":["post-79644","recipe","type-recipe","status-publish","has-post-thumbnail","hentry","intolerance-senza-lattosio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano\" \/>\n<meta property=\"og:description\" content=\"Ingredienti300 g di farina 00 3 uova 200 g di Grana Padano DOP Riserva 500 g di funghi 1 spicchio di aglio 1 cespo di radicchio 1 cipollotto olio extravergine di oliva sale pepePreparazioneSTEP 1Preparate la sfoglia dei ravioli disponendo la farina a fontana in una ciotola, al centro aggiungete le uova e iniziate a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-15T10:46:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/\",\"name\":\"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg\",\"datePublished\":\"2023-04-03T14:46:35+00:00\",\"dateModified\":\"2023-05-15T10:46:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/#breadcrumb\"},\"inLanguage\":\"it-it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-it\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg\",\"width\":395,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-it\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/","og_locale":"it_IT","og_type":"article","og_title":"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano","og_description":"Ingredienti300 g di farina 00 3 uova 200 g di Grana Padano DOP Riserva 500 g di funghi 1 spicchio di aglio 1 cespo di radicchio 1 cipollotto olio extravergine di oliva sale pepePreparazioneSTEP 1Preparate la sfoglia dei ravioli disponendo la farina a fontana in una ciotola, al centro aggiungete le uova e iniziate a [&hellip;]","og_url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/","og_site_name":"Grana Padano","article_modified_time":"2023-05-15T10:46:14+00:00","og_image":[{"width":395,"height":395,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/","url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/","name":"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/it-it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg","datePublished":"2023-04-03T14:46:35+00:00","dateModified":"2023-05-15T10:46:14+00:00","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/#breadcrumb"},"inLanguage":"it-it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/"]}]},{"@type":"ImageObject","inLanguage":"it-it","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/04\/Ravioli-ai-funghi-con-spadellata-di-radicchio-e-Grana-Padano-Riserva-p-IMG_2371.jpg","width":395,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/ravioli-ai-funghi-con-spadellata-di-radicchio-e-grana-padano-riserva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/it-it\/"},{"@type":"ListItem","position":2,"name":"Ravioli ai funghi con spadellata di radicchio e Grana Padano Riserva"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/it-it\/#website","url":"https:\/\/www.granapadano.it\/it-it\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/it-it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-it"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/79644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/comments?post=79644"}],"version-history":[{"count":5,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/79644\/revisions"}],"predecessor-version":[{"id":98739,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/79644\/revisions\/98739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media\/98765"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media?parent=79644"}],"wp:term":[{"taxonomy":"recipe_cat","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe_cat?post=79644"},{"taxonomy":"stagionatura","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/stagionatura?post=79644"},{"taxonomy":"variety","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/variety?post=79644"},{"taxonomy":"tempo","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/tempo?post=79644"},{"taxonomy":"intolerance","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/intolerance?post=79644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}