{"id":49516,"date":"2023-02-23T09:23:25","date_gmt":"2023-02-23T09:23:25","guid":{"rendered":"https:\/\/www.granapadano.it\/recipe\/bocconcini-di-montone-croccanti-con-crema-di-gorgonzola-copy\/"},"modified":"2026-04-08T13:15:56","modified_gmt":"2026-04-08T13:15:56","slug":"quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto","status":"publish","type":"recipe","link":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/","title":{"rendered":"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-h.jpg&#8221; title_text=&#8221;Quenelle di gamberi e calamaro con fonduta-m&#8221; src_tablet=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-h-1.jpg&#8221; src_phone=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-m.jpg&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;single_recipe_content&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;13px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221;recipe_filter_section&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;|auto|-60px|auto|false|false&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||16px|||&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div>[\/et_pb_code][et_pb_code module_class=&#8221;recipe_likes_section&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"49516\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>9<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg&description=Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano Riserva<\/span><\/div>[\/et_pb_code][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Merriweather||||||||&#8221; title_text_color=&#8221;#000000&#8243; title_font_size=&#8221;56px&#8221; title_font_size_tablet=&#8221;56px&#8221; title_font_size_phone=&#8221;36px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;recipe_display&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; min_height=&#8221;40px&#8221; custom_padding=&#8221;1px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Difficulty&#8221; _builder_version=&#8221;4.19.2&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZGlmZmljdWx0eSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxpbWcgc3JjPVwiL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDIyLzExL0dyb3VwLTM5My5zdmdcIj4iLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib2ZmIn19@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Persons&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfU2VydmVzIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiPGltZyBzcmM9XCIvd3AtY29udGVudC91cGxvYWRzLzIwMjIvMTEvR3JvdXAtMzgyLnN2Z1wiPiIsImFmdGVyIjoiIiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Duration&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZHVyYXRpb24iLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiJbdGltZV9pbWddIiwiYWZ0ZXIiOiIiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; min_height=&#8221;40px&#8221; custom_padding=&#8221;1px||11px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Difficulty&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;MerriweatherItalic||on||||||&#8221; header_font=&#8221;MerriweatherItalic||||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Chef Andrea Palumbo<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Persons&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;CheltenhamStd-LightItalic||on||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Senza Lattosio<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;CheltenhamStd-LightItalic||on||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Senza glutine<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;ingredient_sec&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-6px|||||&#8221; custom_padding=&#8221;4px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-29px|auto||auto||&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;0px||3px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; ab_subject=&#8221;on&#8221; ab_subject_id=&#8221;1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Questa ricetta \u00e8 tratta dal Progetto Crossroad, a cura del Consorzio per la Tutela del Grana Padano in collaborazione con la Regione Lombardia e Union Camere. Il progetto \u00e8 nato per la diffusione del marchio Grana Padano in Cina e dei prodotti lombardi a marchio di qualit\u00e0: una sintesi perfetta di promozione commerciale e valorizzazione culturale.<br \/>\nObiettivo del progetto \u00e8 promuovere la versatilit\u00e0 dei prodotti italiani di qualit\u00e0 anche nelle cucine etniche, con particolare riguardo a quella cinese che vanta una lunga storia e tradizione, proprio come quella italiana.<br \/>\nI prodotti DOP italiani incontrano il gusto dei consumatori stranieri non solo nelle ricette italiane ma possono essere utilizzati anche nelle cucine fusion per creare abbinamenti originali e diversi.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;0px||3px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; disabled=&#8221;on&#8221; ab_subject=&#8221;on&#8221; ab_subject_id=&#8221;2&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>In questa ricetta fondamentale \u00e8 l\u2019uso del Grana Padano in quanto indispensabile per la buona riuscita della stessa. Con il suo robusto sapore, contrasta l\u2019acido della salsa ottenuta. Viene considerata a \u201czerosprechi\u201d in quanto viene usata al massimo la parte edibile ma anche perch\u00e9 viene ridotto al minimo l\u2019uso di gas, o di forni usando la minor quantit\u00e0 possibile di energia elettrica.<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;-19px|auto||auto||&#8221; custom_padding=&#8221;6px|||||&#8221; ab_goal=&#8221;on&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Ingredienti&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span>Ingredienti<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Ingredienti List&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;Merriweather||||||||&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;23px&#8221; header_4_line_height=&#8221;36px&#8221; width=&#8221;87%&#8221; custom_padding=&#8221;|30px||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>300 gr di gamberi<br \/>\n300 gr di calamari<br \/>\n100 gr di pane raffermo<br \/>\n600 gr di zucchine<br \/>\n250 ml di latte<br \/>\n120 gr di Grana Padano Riserva<br \/>\n20 gr di pesto di basilico<br \/>\nMaizena<br \/>\nOlio extra vergine di oliva<br \/>\nSale e pepe<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||-2px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Preparazione<\/h1>\n<p>&nbsp;<\/p>\n<h1><\/h1>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 1<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-1-20203.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi&#8211;1-20203&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||29px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span><strong>Per Quenelle di gamberi e calamari:<\/strong><br \/>Pulire i calamari e tritarli finemente. Compiere gli stessi passaggi per i gamberi. Una volta ottenuto il trito dei due elementi, unirli, mescolare ed aggiungere maizena fin quando il composto non risulti sufficientemente denso per poter comporre le quenelle. Condire con sale e pepe.<br \/><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Il Consorzio di Tutela del Grana Padano ha deciso di far conoscere i Giovani allevatori che rappresentano un motore potente di crescita e di innovazione.<br \/>Seguiteci, sar\u00e0 una continua ed emozionante scoperta di passione, impegno e speranza per il futuro.<\/h4>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 2<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-2-20204.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-2-20204&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Prendere il pane raffermo, grattugiarlo grossolanamente e in una padella dorarlo con un filo d&#8217;olio e lasciar raffreddare.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 3<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-3-20205.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-3-20205&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Comporre 12 Quenelle con il trito di gamberi e calamari e passarle nel pane grattugiato. Friggerle in padella con abbastanza olio da coprirne il fondo, a fiamma alta. Quando risultano dorate, scolare e conservare al caldo.<br \/>\n<\/span><\/h4>\n<p>&nbsp;[\/et_pb_text][et_pb_text disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 4<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span><strong>Per fonduta di Grana Padano:<\/strong><br \/>Ottenere delle scaglie sottili di Grana Padano. In un pentolino riscaldare il latte a fiamma molto bassa, aggiungere poco alla volta il formaggio e mescolare lentamente. Quando il Grana Pdano risulter\u00e0 sciolto, aggiungere l\u2019amido di mais, mescolare finch\u00e9 la fonduta non si addensa (non deve essere n\u00e9 filante ne farinosa) e conservare al caldo.<br \/>Serve hot.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 5<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span><strong>Per crema di zucchine profumata al pesto:<\/strong><br \/>Con l\u2019ausilio di un pelapatate pelare le zucchine (solo parte verde). Tritare e scottare in padella con un filo d&#8217;olio. Frullare il tutto, aggiungere il pesto di basilico e mescolare.<br \/>Finitura del piatto<br \/>Comporre il piatto con 3 quenelle al centro, versare la fonduta di Grana Padano, aggiungere la crema di zucchine profumata al pesto e servire caldo.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 6<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span><strong>Il pane a tavola:<\/strong><br \/>Sulla tavola di questo mese c\u2019\u00e8 anche il piattino per il pane, in alto, a sinistra. Non \u00e8 obbligatorio, soprattutto se si tratta di una tavola informale, come quella di una domenica passata in famiglia.<br \/>Tuttavia, pu\u00f2 essere anche un elemento decorativo. In pi\u00f9, se apparecchiamo la tavola con delle tovagliette all\u2019americana, la fetta di pane andrebbe a diretto contatto con il tavolo nudo, cosa che \u00e8 sempre da evitare.<br \/>Non avete il piattino del pane? Si pu\u00f2 benissimo utilizzare quello della tazzina del caff\u00e8, non bisogna necessariamente acquistarne uno apposta.<br \/>Mentre potrebbe essere entusiasmante andare per mercatini dell\u2019usato o scovare tra i piatti della nonna per trovarne di diversi decori e fogge, cosa che renderebbe la tavola un po\u2019 stravagante ma piacevolmente divertente.<\/span><\/h4>\n<h4>In ogni caso, il pane, che se si tratta di una pagnotta va opportunamente tagliato a fette sottili, va sempre messo in un cestino, su un tovagliolo ben pulito. Ognuno se ne serve senza indugiare troppo e senza tastare i pezzi per scegliere quello che pi\u00f9 piace.<br \/>Se invece vogliamo portare a tavola del pane appena sfornato (casomai fatto in casa), possiamo disporlo su un tagliere di legno ed utilizzare un tovagliolo per agevolare chi taglier\u00e0 il pane, in modo che non lo tocchi con le proprie mani.<\/h4>\n<h4>Come si mangia il pane?<br \/>Non si taglia con il coltello, ma si spezza con le mani, e si porta alla bocca con una sola mano, un pezzetto alla volta. Assolutamente scorretto portare alla bocca un grosso pezzo di pane e staccarne un boccone coi denti.<\/h4>\n<h4>Scarpetta si o no?<br \/>\u00c8 ammessa, ma solo nei pranzi familiari, purch\u00e9 il pezzetto di pane non sia tenuto fra le dita, ma infilato nella forchetta. Questo \u00e8 quel che dice il galateo, ma chi resiste alla tentazione di questo buon rag\u00f9 avanzato nel piatto, dopo aver gustato gli gnocchi?<br \/>L\u2019importante \u00e8 conoscere le regole, poi, in casa propria, ognuno sapr\u00e0 regolarsi, no?<\/h4>\n<h4>Infine, non sprechiamo il pane! Pu\u00f2 essere riutilizzato in tenete ricette. La prima, facile ed immediata, \u00e8 intingere le fette di pane nel latte, senza bagnarle troppo, disporle in teglia ben imburrata, spolverare con abbondate Grana Padano grattugiato e fare gratinare in forno per 10 minuti a 180\u00b0C oppure metterle nel microonde alla massima potenza per 30 secondi.<\/h4>\n<p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/file_example_MP4_640_3MG.mp4&#8243; font_icon=&#8221;&#xf144;||fa||900&#8243; thumbnail_overlay_color=&#8221;#000000&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;|||58px||&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather|700|||||||&#8221; header_4_font=&#8221;Merriweather||on||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;24px||46px||false|false&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Chef Andrea Palumbo &#8211; IPSSAR MARCHITELLI &#8211; Villa Santa Maria (CH) &#8211; A scuola di cucina con Grana Padano &#8211; 2015-2016<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_comment_wrapper&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_margin=&#8221;-9px|||||&#8221; custom_padding=&#8221;60px||60px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; max_width=&#8221;90%&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Varianti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather|700|||||||&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;32px&#8221; text_line_height=&#8221;40px&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;40px&#8221; min_height=&#8221;34px&#8221; custom_margin=&#8221;||10px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Varianti<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Varianti Description&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;36px&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-13px||62px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Volete provare la versione di \u201cterra\u201d di questo sfizioso piatto?<br \/>Sostituite il salmone con delle fettine sottili di roast beef, otterrete una variante altrettanto gustosa!<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; header_3_font=&#8221;Merriweather||||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;40px&#8221; custom_margin=&#8221;||15px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Suggerimenti<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti Description&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;36px&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-16px||100px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Si consiglia di servire subito l\u2019avocado, uova e salmone.<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; custom_margin=&#8221;||14px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Informazioni nutrizionali<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Table&#8221; module_class=&#8221;nutrizionali_main&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table>\n<tbody>\n<tr>\n<th>\n<h4>Energia<\/h4>\n<\/th>\n<td>\n<h4>2087,9 KJ \/ 498,6 kcal<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Grassi<\/h4>\n<\/th>\n<td>\n<h4>38,9 g<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Carboidrati<\/h4>\n<\/th>\n<td>\n<h4>29,5 g<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Proteine<\/h4>\n<\/th>\n<td>\n<h4>7,7 g<\/h4>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_comments module_class=&#8221;comment_section&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_comments][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;related_product_wrapper ricette_main_sec&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;97px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span>Ricette Correlate<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;Code&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_main dev_main\"><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/healthy-e-sport\/insalata-di-mandarini-scarola-grana-padano-e-mandorle-tostate\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/INSALATA_MANDARINI_SCAROLA-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>10 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Insalata di mandarini, scarola, Grana Padano e mandorle tostate<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/healthy-e-sport\/insalata-di-scalogno-al-sale-pane-alla-segale-e-fonduta-al-grana-padano-dop-riserva\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Insalata_scalogno_sale-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>30 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 persone <\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Insalata di scalogno al sale, pane alla segale e fonduta al Grana Padano DOP Riserva<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolo-rosso-con-grana-padano\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolo-rosso-con-Grana-Padano-p-GP9339.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Medio<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>60 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Vellutata di cavolo rosso con Grana Padano<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/healthy-e-sport\/insalata-di-ceci-con-grana-padano\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/INSALATA_CECI_GRANA_PADANO-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>15 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Insalata di ceci con Grana Padano<\/h3><\/div><\/div><\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;scopri_btn&#8221; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;13px|auto||auto||&#8221; custom_padding=&#8221;||38px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;\/it-it\/momenti-di-consumo\/&#8221; button_text=&#8221;SCOPRI TUTTE LE RICETTE&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;23px&#8221; button_text_color=&#8221;#0f0f0f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#221f1c&#8221; button_border_radius=&#8221;40px&#8221; button_font=&#8221;Merriweather|700|||||||&#8221; button_icon=&#8221;&#x35;||divi||400&#8243; button_icon_color=&#8221;#000000&#8243; button_on_hover=&#8221;off&#8221; custom_margin=&#8221;-1px|||||&#8221; custom_padding=&#8221;3px||3px|||&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#0f0f0f&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_icon_color__hover_enabled=&#8221;on|hover&#8221; button_icon_color__hover=&#8221;#FFFFFF&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Riso-Acquerello-GP-Fichi-e-Alici-h-3.jpg&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div><div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"49516\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>9<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg&description=Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano Riserva<\/span><\/div>Chef Andrea PalumboSenza LattosioSenza glutineQuesta ricetta \u00e8 tratta dal Progetto Crossroad, a cura del Consorzio per la Tutela del Grana Padano in collaborazione con la Regione Lombardia e Union Camere. Il progetto \u00e8 nato per la diffusione del marchio Grana Padano in Cina e dei prodotti lombardi a marchio di qualit\u00e0: una sintesi perfetta di [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":49536,"menu_order":1863,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"recipe_cat":[3409],"stagionatura":[42],"variety":[],"tempo":[54],"intolerance":[],"class_list":["post-49516","recipe","type-recipe","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano\" \/>\n<meta property=\"og:description\" content=\"Chef Andrea PalumboSenza LattosioSenza glutineQuesta ricetta \u00e8 tratta dal Progetto Crossroad, a cura del Consorzio per la Tutela del Grana Padano in collaborazione con la Regione Lombardia e Union Camere. Il progetto \u00e8 nato per la diffusione del marchio Grana Padano in Cina e dei prodotti lombardi a marchio di qualit\u00e0: una sintesi perfetta di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T13:15:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/\",\"name\":\"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg\",\"datePublished\":\"2023-02-23T09:23:25+00:00\",\"dateModified\":\"2026-04-08T13:15:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/#breadcrumb\"},\"inLanguage\":\"it-it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-it\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg\",\"width\":395,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-it\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/","og_locale":"it_IT","og_type":"article","og_title":"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano","og_description":"Chef Andrea PalumboSenza LattosioSenza glutineQuesta ricetta \u00e8 tratta dal Progetto Crossroad, a cura del Consorzio per la Tutela del Grana Padano in collaborazione con la Regione Lombardia e Union Camere. Il progetto \u00e8 nato per la diffusione del marchio Grana Padano in Cina e dei prodotti lombardi a marchio di qualit\u00e0: una sintesi perfetta di [&hellip;]","og_url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/","og_site_name":"Grana Padano","article_modified_time":"2026-04-08T13:15:56+00:00","og_image":[{"width":395,"height":395,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/","url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/","name":"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/it-it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg","datePublished":"2023-02-23T09:23:25+00:00","dateModified":"2026-04-08T13:15:56+00:00","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/#breadcrumb"},"inLanguage":"it-it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/"]}]},{"@type":"ImageObject","inLanguage":"it-it","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Quenelle-di-gamberi-e-calamaro-con-fonduta-p.jpg","width":395,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/quenelle-di-gamberi-e-calamaro-con-fonduta-di-grana-padano-e-crema-di-zucchine-profumata-al-pesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/it-it\/"},{"@type":"ListItem","position":2,"name":"Quenelle di gamberi e calamaro con fonduta di Grana Padano e crema di zucchine profumata al pesto"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/it-it\/#website","url":"https:\/\/www.granapadano.it\/it-it\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/it-it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-it"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/49516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/comments?post=49516"}],"version-history":[{"count":2,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/49516\/revisions"}],"predecessor-version":[{"id":154633,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/49516\/revisions\/154633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media\/49536"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media?parent=49516"}],"wp:term":[{"taxonomy":"recipe_cat","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe_cat?post=49516"},{"taxonomy":"stagionatura","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/stagionatura?post=49516"},{"taxonomy":"variety","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/variety?post=49516"},{"taxonomy":"tempo","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/tempo?post=49516"},{"taxonomy":"intolerance","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/intolerance?post=49516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}