{"id":47111,"date":"2023-02-22T09:43:40","date_gmt":"2023-02-22T09:43:40","guid":{"rendered":"https:\/\/www.granapadano.it\/recipe\/spaghetti-integrali-con-verdure-e-crema-di-grana-padano-copy\/"},"modified":"2023-04-02T21:19:54","modified_gmt":"2023-04-02T21:19:54","slug":"vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva","status":"publish","type":"recipe","link":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/","title":{"rendered":"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-h.jpg&#8221; title_text=&#8221;Vellutata di cavolfiore e curcuma con nocciole, salvia-m&#8221; src_tablet=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-h-1.jpg&#8221; src_phone=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-m.jpg&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;single_recipe_content&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;13px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221;recipe_filter_section&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;|auto|-60px|auto|false|false&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||16px|||&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div>[\/et_pb_code][et_pb_code module_class=&#8221;recipe_likes_section&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"47111\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>19<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg&description=Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano<\/span><span class=\"tax_name\">Zuppe<\/span><\/div>[\/et_pb_code][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Merriweather||||||||&#8221; title_text_color=&#8221;#000000&#8243; title_font_size=&#8221;56px&#8221; title_font_size_tablet=&#8221;56px&#8221; title_font_size_phone=&#8221;36px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;recipe_display&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; min_height=&#8221;40px&#8221; custom_padding=&#8221;1px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Difficulty&#8221; _builder_version=&#8221;4.19.2&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZGlmZmljdWx0eSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxpbWcgc3JjPVwiL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDIyLzExL0dyb3VwLTM5My5zdmdcIj4iLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib2ZmIn19@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Persons&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfU2VydmVzIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiPGltZyBzcmM9XCIvd3AtY29udGVudC91cGxvYWRzLzIwMjIvMTEvR3JvdXAtMzgyLnN2Z1wiPiIsImFmdGVyIjoiIiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Duration&#8221; _builder_version=&#8221;4.19.4&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; width=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfZHVyYXRpb24iLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiJbdGltZV9pbWddIiwiYWZ0ZXIiOiIiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; min_height=&#8221;40px&#8221; custom_padding=&#8221;1px||11px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Difficulty&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;MerriweatherItalic||on||||||&#8221; header_font=&#8221;MerriweatherItalic||||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Danilo Cortellini<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Persons&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;CheltenhamStd-LightItalic||on||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Senza Lattosio<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;CheltenhamStd-LightItalic||on||||||&#8221; custom_margin=&#8221;10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Senza glutine<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;ingredient_sec&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-6px|||||&#8221; custom_padding=&#8221;4px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-29px|auto||auto||&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;0px||3px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; disabled=&#8221;on&#8221; ab_subject=&#8221;on&#8221; ab_subject_id=&#8221;1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Sono cresciuto in un&#8217;umile famiglia, in quella che fino a pochi anni fa veniva considerata una zona rurale della penisola italiana. Il cibo \u00e8 sempre stato il centro della nostra vita sociale; ogni occasione famigliare \u00e8 stata celebrata seduti a tavola e, per questo, abbiamo sviluppato un grande rispetto per i prodotti davanti a noi. Sapevamo che per produrre quegli ingredienti ci voleva fatica e per la nostra famiglia acquistarli significava fare dei sacrifici. Questi sono i motivi principali per cui nella nostra cultura \u00e8 ben radicata l\u2019arte di sfruttare ogni ingrediente al massimo delle sue capacit\u00e0. Se cerchi abbastanza in profondit\u00e0 da scoprire tutto il suo potenziale, rimarrai stupito da quanto sapore si pu\u00f2 ricavare da un ingrediente.<br \/>Prendi per esempio la crosta del Grana Padano, buttarla via nella mia famiglia avrebbe provocato una rivolta! C\u2019\u00e8 cos\u00ec tanto che puoi fare con essa, dalla creazione di crostini soffiati al cuocerla lentamente sul barbecue, gli usi di questa parte trascurata di formaggio sono infiniti. Il modo pi\u00f9 semplice e antico di utilizzarla \u00e8 di metterla semplicemente nella zuppa, nel brodo e nelle salse. Aggiunger\u00e0 un sapore extra alla tua preparazione. Ovviamente, bisogna spazzolarla bene prima dell\u2019uso.<\/span><\/h4>\n<h4>In questa ricetta, puoi tagliare la crosta cotta in cubetti e metterli nella zuppa. Che delizia!<\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;0px||3px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; disabled=&#8221;on&#8221; ab_subject=&#8221;on&#8221; ab_subject_id=&#8221;2&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>In questa ricetta fondamentale \u00e8 l\u2019uso del Grana Padano in quanto indispensabile per la buona riuscita della stessa. Con il suo robusto sapore, contrasta l\u2019acido della salsa ottenuta. Viene considerata a \u201czerosprechi\u201d in quanto viene usata al massimo la parte edibile ma anche perch\u00e9 viene ridotto al minimo l\u2019uso di gas, o di forni usando la minor quantit\u00e0 possibile di energia elettrica.<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;-19px|auto||auto||&#8221; custom_padding=&#8221;6px|||||&#8221; ab_goal=&#8221;on&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Ingredienti&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span>Ingredienti<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Ingredienti List&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;Merriweather||||||||&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;23px&#8221; header_4_line_height=&#8221;36px&#8221; width=&#8221;87%&#8221; custom_padding=&#8221;|30px||||&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4>1 cavolfiore<br \/>\n100 g di Grana Padano Riserva<br \/>\n2 patata<br \/>\n1 L di brodo vegetale<br \/>\n1 cucchiaino di curcuma<br \/>\n80 g di Nocciole Piemonte IGP<br \/>\n1 ciuffo di salvia<br \/>\nolio extravergine di oliva<br \/>\nsale<br \/>\npepe<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||-2px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Preparazione<\/p>\n<h1>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 1<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-1-20203.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi&#8211;1-20203&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||29px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4><span>Prendete il cavolfiore e tagliate le cimette, sbucciate le patate e tagliatele a tocchetti, mettete tutto in una pentola, coprite con il brodo e fate cuocere per 30 minuti. Aggiustate di sale e pepe, aggiungete la curcuma e frullate tutto con un mixer a immersione, fino a ottenere una crema morbida.<br \/>\n<\/span><\/h4>\n<p>&nbsp;[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Il Consorzio di Tutela del Grana Padano ha deciso di far conoscere i Giovani allevatori che rappresentano un motore potente di crescita e di innovazione.<br \/>Seguiteci, sar\u00e0 una continua ed emozionante scoperta di passione, impegno e speranza per il futuro.<\/h4>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 2<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-2-20204.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-2-20204&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4><span>In una padella antiaderente fate tostare le nocciole tritate grossolanamente con un filo di olio extravergine di oliva, sale, pepe e le foglie di salvia.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 3<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-3-20205.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-3-20205&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4><span>Servite la vellutata calda, con le nocciole croccanti, salvia e Grana Padano Riserva grattugiato.<br \/>\n<\/span><\/h4>\n<p>&nbsp;[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221; disabled=&#8221;on&#8221;]<\/p>\n<p>STEP 4<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h4><span>Saltate gli spaghetti con le verdure, sciogliete il Grana Padano con il mestolo di acqua calda di cottura. Servite subito la pasta con le verdure aggiungendo la crema di Grana Padano.<br \/>\n<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 5<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/01\/Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206.jpg&#8221; title_text=&#8221;Crostatina-di-Zucca-e-Grana-Padano-miele-e-lamponi-4-20206&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Image&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||30px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Ripetete l\u2019operazione riempiendo la teglia fino ad ottenere 4-5 strati di pasta.<br \/>\nFate cuocere le lasagne in forno preriscaldato a 180\u00b0C per 15-20 minuti<br \/>\nServite le lasagne ancora calde.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_single_button&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather||on||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;26px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; transform_scale=&#8221;90%|90%&#8221; text_orientation=&#8221;center&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;24%&#8221; width_phone=&#8221;25%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px||20px|-10px|false|false&#8221; custom_padding=&#8221;15px|20px|15px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; border_style_all=&#8221;none&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93}&#8221;]<\/p>\n<p>STEP 6<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-20px||46px|||&#8221; custom_padding=&#8221;20px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span><strong>Per la guarnizione:<\/strong><br \/>Tagliare i pomodorini a quadratini e cospargerli con un pizzico di sale e zucchero in superficie. Metterli in una teglia con dell\u2019olio evo e lasciar cuocere a 140\u00b0C in forno statico preriscaldato per circa 2 ore, fino a quando l\u2019acqua di vegetazione dei pomodorini non sar\u00e0 evaporata e questi risulteranno leggermente abbrustoliti ma non secchi.<br \/>Coprire il fondo del piatto con la crema di mela, adagiare la quenelle, posizionare la rete, sopra di essa l\u2019aria con la cialda di pane e completare con i pomodorini.<br \/><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/file_example_MP4_640_3MG.mp4&#8243; font_icon=&#8221;&#xf144;||fa||900&#8243; thumbnail_overlay_color=&#8221;#000000&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;|||58px||&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Step Description&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather|700|||||||&#8221; header_4_font=&#8221;Merriweather||on||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;24px||46px||false|false&#8221; custom_padding=&#8221;20px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span>Chef Dante Florian &#8211; IPSSAR MARTINI di Montecatini Terme PT &#8211; A scuola di cucina con Grana Padano &#8211; 2016-2017<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;recipe_comment_wrapper&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_margin=&#8221;-9px|||||&#8221; custom_padding=&#8221;60px||60px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; max_width=&#8221;90%&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Varianti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Merriweather|700|||||||&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;32px&#8221; text_line_height=&#8221;40px&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;40px&#8221; min_height=&#8221;34px&#8221; custom_margin=&#8221;||10px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Varianti<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Varianti Description&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;36px&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-13px||62px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Volete provare la versione di \u201cterra\u201d di questo sfizioso piatto?<br \/>Sostituite il salmone con delle fettine sottili di roast beef, otterrete una variante altrettanto gustosa!<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; header_3_font=&#8221;Merriweather||||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;40px&#8221; custom_margin=&#8221;||15px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Suggerimenti<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti Description&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;36px&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;27px&#8221; custom_margin=&#8221;-16px||100px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Si consiglia di servire subito l\u2019avocado, uova e salmone.<\/h4>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Suggerimenti&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#0f0f0f&#8221; header_3_font_size=&#8221;32px&#8221; custom_margin=&#8221;||14px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Informazioni nutrizionali<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Table&#8221; module_class=&#8221;nutrizionali_main&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Merriweather||||||||&#8221; header_4_font_size=&#8221;21px&#8221; header_4_line_height=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table>\n<tbody>\n<tr>\n<th>\n<h4>Energia<\/h4>\n<\/th>\n<td>\n<h4>2087,9 KJ \/ 498,6 kcal<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Grassi<\/h4>\n<\/th>\n<td>\n<h4>38,9 g<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Carboidrati<\/h4>\n<\/th>\n<td>\n<h4>29,5 g<\/h4>\n<\/td>\n<\/tr>\n<tr>\n<th>\n<h4>Proteine<\/h4>\n<\/th>\n<td>\n<h4>7,7 g<\/h4>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_comments module_class=&#8221;comment_section&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_comments][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;related_product_wrapper ricette_main_sec&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;97px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Ricette correlate<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;Code&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"recipe_main dev_main\"><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/aperisnack-e-spuntini\/alberelli-di-natale-di-pasta-sfoglia-prosciutto-e-grana-padano\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Alberelli-di-natale-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile <\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>30 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Alberelli di Natale di pasta sfoglia, prosciutto e Grana Padano<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/aperisnack-e-spuntini\/baci-di-frolla-al-grana-padano-dop-caprino-granella-di-pistacchi-e-fiori-secchi\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/GPPIATTI0071-50404-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>140 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Baci Di Frolla Al Grana Padano Dop, Caprino, Granella Di Pistacchi E Fiori Secchi<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/carciofi-e-patate-al-forno-con-grana-padano\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Carciofi-e-patate-al-forno-con-Grana-Padano-p-IMG_6356.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>60 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>4 per.<\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Carciofi e patate al forno con Grana Padano<\/h3><\/div><\/div><\/a><a href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/aperisnack-e-spuntini\/canestrello-di-borgofranco-divrea-salato-alle-erbe-fini-con-grana-padano-riserva-oltre-20-mesi-crudo-di-parma-e-insalatina-con-sfere-al-balsamico\/\"><div class=\"recipe_item\"><div class=\"recipe_img\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/canestrello-di-borgofranco-p.jpg\" \/><span class=\"show_recipe\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\"\/><\/span><\/div><table width=\"100%\" border=\"0\" cellspacing=\"5\" cellpadding=\"5\"><tbody><tr class=\"inforecipebasse\" style=\"padding-left: 0px !Important; border: 0px !Important;\"><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"8\" height=\"8\" viewBox=\"0 0 8 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"\"><path d=\"M2.5 1.5L2.09375 1.20312C1.92188 1.07812 1.71875 1 1.5 1C0.9375 1 0.5 1.45312 0.5 2V2.03125C0.5 2.125 0.515625 2.23438 0.53125 2.32812L1.35938 5H2.15625L1.75 2.79688L1.70312 2.5625L2.1875 2.46875L2.23438 2.71875L2.65625 4.96875V5H3.75V2.25V2H4.25V2.25V5H5.32812V4.96875L5.75 2.71875L5.79688 2.46875L6.28125 2.5625L6.23438 2.79688L5.82812 5H6.625L7.45312 2.32812C7.46875 2.23438 7.48438 2.125 7.48438 2.03125V2C7.48438 1.45312 7.04688 1 6.48438 1C6.26562 1 6.0625 1.07812 5.89062 1.20312L5.5 1.5L5.1875 1.10938C4.92188 0.734375 4.48438 0.5 4 0.5C3.5 0.5 3.0625 0.734375 2.79688 1.10938L2.5 1.5ZM7 5.5H1L0.0625 2.46875C0.015625 2.32812 0 2.1875 0 2.03125V2C0 1.17188 0.671875 0.5 1.5 0.5C1.82812 0.5 2.14062 0.625 2.39062 0.8125C2.76562 0.328125 3.34375 0 4 0C4.64062 0 5.23438 0.328125 5.59375 0.8125C5.84375 0.625 6.15625 0.5 6.5 0.5C7.32812 0.5 8 1.17188 8 2V2.03125C8 2.1875 7.96875 2.32812 7.92188 2.46875L7 5.5ZM1 6H1.5V7.5H6.5V6H7V7.5V8H6.5H1.5H1V7.5V6Z\" fill=\"#876346\"><\/path><\/svg> Difficolt\u00e0<br><\/span><span class=\"recipe_tags\"><p>Facile <\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"7\" height=\"8\" viewBox=\"0 0 7 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0.5 3.5C0.5 4.57812 1.0625 5.5625 2 6.10938C2.92188 6.64062 4.0625 6.64062 5 6.10938C5.92188 5.5625 6.5 4.57812 6.5 3.5C6.5 2.4375 5.92188 1.45312 5 0.90625C4.0625 0.375 2.92188 0.375 2 0.90625C1.0625 1.45312 0.5 2.4375 0.5 3.5ZM6.5 5.3125C5.875 6.32812 4.76562 7 3.5 7C2.21875 7 1.10938 6.32812 0.5 5.3125V7.5H6.5V5.3125ZM0 3.5C0 1.57812 1.5625 0 3.5 0C5.42188 0 7 1.57812 7 3.5V7.75V8H6.75H0.25H0V7.75V3.5ZM3.75 1.5V1.75V3.40625L4.42188 4.07812L4.59375 4.25L4.25 4.60938L4.0625 4.4375L3.3125 3.6875L3.25 3.60938V3.5V1.75V1.5H3.75Z\" fill=\"#876346\"><\/path><\/svg> Preparazione<br><\/span><span class=\"recipe_tags\"><p>75 min<\/p><\/span><\/td><td class=\"inforecipebassetd\"><span style=\"display: flex; align-items: center; padding:0px; text-align: left; font-size: 12px !Important; color:#876346; text-align: left; padding: 0px !important;\"><svg style=\"display:none !important;\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M5.1875 1.32812L7.01562 0L7.375 0.359375L5.48438 1.73438C5.4375 1.76562 5.39062 1.8125 5.34375 1.85938L5.3125 1.875C5.10938 2.09375 5 2.375 5 2.65625C5 2.95312 5.10938 3.23438 5.3125 3.45312L5.51562 3.65625C5.73438 3.85938 6.01562 3.96875 6.3125 3.96875C6.59375 3.96875 6.875 3.85938 7.09375 3.65625L7.10938 3.625C7.15625 3.57812 7.20312 3.53125 7.23438 3.48438L8.625 1.59375L8.96875 1.95312L7.64062 3.78125C7.57812 3.85938 7.53125 3.92188 7.46875 3.98438L7.4375 4C7.14062 4.3125 6.73438 4.46875 6.3125 4.46875C5.92188 4.46875 5.53125 4.32812 5.25 4.07812L1.42188 7.90625L1.0625 7.54688L4.89062 3.71875C4.64062 3.4375 4.5 3.04688 4.5 2.65625C4.5 2.23438 4.65625 1.82812 4.96875 1.53125L4.98438 1.5C5.04688 1.4375 5.10938 1.39062 5.1875 1.32812ZM5.4375 2.40625L7.5625 0.546875L7.92188 0.90625L5.76562 2.78125L5.65625 2.89062L5.29688 2.53125L5.4375 2.40625ZM6.4375 3.67188L6.07812 3.3125L6.1875 3.20312L8.0625 1.04688L8.42188 1.40625L6.5625 3.53125L6.4375 3.67188ZM0.71875 0.1875L0.90625 0.03125L1.07812 0.203125L4.28125 3.625L3.92188 3.98438L0.890625 0.75C0.859375 0.796875 0.8125 0.84375 0.78125 0.921875C0.640625 1.14062 0.5 1.46875 0.5 1.84375C0.5 2.17188 0.640625 2.57812 1.03125 3.15625C1.40625 3.70312 1.96875 4.34375 2.76562 5.14062L2.40625 5.5C1.60938 4.6875 1.01562 4.01562 0.625 3.4375C0.21875 2.84375 0 2.3125 0 1.84375C0 1.34375 0.171875 0.9375 0.359375 0.65625C0.453125 0.5 0.53125 0.390625 0.609375 0.3125C0.640625 0.28125 0.671875 0.25 0.6875 0.21875C0.703125 0.21875 0.703125 0.203125 0.71875 0.203125V0.1875C0.71875 0.1875 0.71875 0.1875 0.890625 0.375L0.71875 0.1875ZM7.60938 7.95312L4.95312 5.07812L5.29688 4.73438L7.96875 7.60938L7.60938 7.95312Z\" fill=\"#876346\"><\/path><\/svg> Dosi per<br><\/span><span class=\"recipe_tags\"><p>6 per. <\/p><\/span><\/td><\/tr><\/tbody><\/table><div class=\"recipe_title\"><h3>Canestrello di Borgofranco d\u2019Ivrea salato alle erbe fini con Grana Padano Riserva Oltre 20 mesi, crudo di Parma e insalatina con sfere al balsamico<\/h3><\/div><\/div><\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;scopri_btn&#8221; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;13px|auto||auto||&#8221; custom_padding=&#8221;||38px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/www.granapadano.it\/momenti-di-consumo\/&#8221; button_text=&#8221;SCOPRI TUTTE LE RICETTE&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;23px&#8221; button_text_color=&#8221;#0f0f0f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#221f1c&#8221; button_border_radius=&#8221;40px&#8221; button_font=&#8221;Merriweather|700|||||||&#8221; button_icon=&#8221;&#x35;||divi||400&#8243; button_icon_color=&#8221;#000000&#8243; button_on_hover=&#8221;off&#8221; custom_margin=&#8221;-1px|||||&#8221; custom_padding=&#8221;3px||3px|||&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#0f0f0f&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_icon_color__hover_enabled=&#8221;on|hover&#8221; button_icon_color__hover=&#8221;#FFFFFF&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/it-it\/\">Home<\/a>  <  <\/div><div class=\"recipe_social_main\"><div class=\"recipe_like_section \"><a href=\"javascript:\" class=\"recipe_like_btn dev_like_btn\" data-id=\"47111\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/like_thumb.png\"><span>Mi piace<\/span><\/a><\/div><div class=\"recipe_liked_count dev_liked_count\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/heart_like.png\"><span>Piace a <em>19<\/em><\/span><\/div><div class=\"recipe_social_share\"><p>Condividi<\/p><ul><li><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fb.png\"><\/a><\/li><li><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/&media=https:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg&description=Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/print.png\"><\/a><\/li><li><a href=\"https:\/\/twitter.com\/share?text=Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva&url=https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" class=\"recipe_like_btn\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/twitter.png\"><\/a><\/li><ul><\/div><\/div><div class=\"related_tax\"><span class=\"tax_name\">Grana Padano<\/span><span class=\"tax_name\">Zuppe<\/span><\/div>Danilo CortelliniSenza LattosioSenza glutineSono cresciuto in un&#8217;umile famiglia, in quella che fino a pochi anni fa veniva considerata una zona rurale della penisola italiana. Il cibo \u00e8 sempre stato il centro della nostra vita sociale; ogni occasione famigliare \u00e8 stata celebrata seduti a tavola e, per questo, abbiamo sviluppato un grande rispetto per i prodotti [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":47126,"menu_order":1941,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1920","footnotes":""},"recipe_cat":[3409],"stagionatura":[41],"variety":[47],"tempo":[53],"intolerance":[],"class_list":["post-47111","recipe","type-recipe","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano\" \/>\n<meta property=\"og:description\" content=\"Danilo CortelliniSenza LattosioSenza glutineSono cresciuto in un&#039;umile famiglia, in quella che fino a pochi anni fa veniva considerata una zona rurale della penisola italiana. Il cibo \u00e8 sempre stato il centro della nostra vita sociale; ogni occasione famigliare \u00e8 stata celebrata seduti a tavola e, per questo, abbiamo sviluppato un grande rispetto per i prodotti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-02T21:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/\",\"name\":\"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg\",\"datePublished\":\"2023-02-22T09:43:40+00:00\",\"dateModified\":\"2023-04-02T21:19:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/#breadcrumb\"},\"inLanguage\":\"it-it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-it\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg\",\"width\":395,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/ricette\\\/tradizione-italiana\\\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-it\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/","og_locale":"it_IT","og_type":"article","og_title":"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano","og_description":"Danilo CortelliniSenza LattosioSenza glutineSono cresciuto in un'umile famiglia, in quella che fino a pochi anni fa veniva considerata una zona rurale della penisola italiana. Il cibo \u00e8 sempre stato il centro della nostra vita sociale; ogni occasione famigliare \u00e8 stata celebrata seduti a tavola e, per questo, abbiamo sviluppato un grande rispetto per i prodotti [&hellip;]","og_url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/","og_site_name":"Grana Padano","article_modified_time":"2023-04-02T21:19:54+00:00","og_image":[{"width":395,"height":395,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/","url":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/","name":"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/it-it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg","datePublished":"2023-02-22T09:43:40+00:00","dateModified":"2023-04-02T21:19:54+00:00","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/#breadcrumb"},"inLanguage":"it-it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/"]}]},{"@type":"ImageObject","inLanguage":"it-it","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-p.jpg","width":395,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/it-it\/ricette\/tradizione-italiana\/vellutata-di-cavolfiore-e-curcuma-con-nocciole-salvia-e-grana-padano-riserva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/it-it\/"},{"@type":"ListItem","position":2,"name":"Vellutata di cavolfiore e curcuma con nocciole, salvia e Grana Padano Riserva"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/it-it\/#website","url":"https:\/\/www.granapadano.it\/it-it\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/it-it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-it"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/47111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/comments?post=47111"}],"version-history":[{"count":0,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe\/47111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media\/47126"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/media?parent=47111"}],"wp:term":[{"taxonomy":"recipe_cat","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/recipe_cat?post=47111"},{"taxonomy":"stagionatura","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/stagionatura?post=47111"},{"taxonomy":"variety","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/variety?post=47111"},{"taxonomy":"tempo","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/tempo?post=47111"},{"taxonomy":"intolerance","embeddable":true,"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/intolerance?post=47111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}