{"id":2936,"count":5,"description":"","link":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/","name":"Bergamo","slug":"bergamo","taxonomy":"provincia","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bergamo Archives - Grana Padano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bergamo Archives - Grana Padano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/provincia\\\/bergamo\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/provincia\\\/bergamo\\\/\",\"name\":\"Bergamo Archives - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/provincia\\\/bergamo\\\/#breadcrumb\"},\"inLanguage\":\"it-it\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/provincia\\\/bergamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bergamo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/it-it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-it\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bergamo Archives - Grana Padano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/","og_locale":"it_IT","og_type":"article","og_title":"Bergamo Archives - Grana Padano","og_url":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/","og_site_name":"Grana Padano","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/","url":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/","name":"Bergamo Archives - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/it-it\/#website"},"breadcrumb":{"@id":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/#breadcrumb"},"inLanguage":"it-it"},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/it-it\/provincia\/bergamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/it-it\/"},{"@type":"ListItem","position":2,"name":"Bergamo"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/it-it\/#website","url":"https:\/\/www.granapadano.it\/it-it\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/it-it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-it"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/provincia\/2936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/provincia"}],"about":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/taxonomies\/provincia"}],"wp:post_type":[{"href":"https:\/\/www.granapadano.it\/it-it\/wp-json\/wp\/v2\/consortium?provincia=2936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}