{"id":82116,"date":"2023-02-13T14:11:59","date_gmt":"2023-02-13T14:11:59","guid":{"rendered":"https:\/\/www.granapadano.it\/consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/"},"modified":"2026-01-13T15:52:12","modified_gmt":"2026-01-13T15:52:12","slug":"caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc","status":"publish","type":"consortium","link":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/","title":{"rendered":"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_code _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_section global_module=\"17795 \"][\/et_pb_section][\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;production_sub_hub_main_wrapper&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;13px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221;recipe_filter_section&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/fr-fr\/\">Home<\/a>  <  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; module_class=&#8221;consortium_main_section&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.20.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Merriweather|700|||||||&#8221; header_text_color=&#8221;#221f1c&#8221; header_font_size=&#8221;44px&#8221; header_line_height=&#8221;52px&#8221; width=&#8221;96.7%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Caseificio di Prabiano di Renofio Enrico Erminio e figlio <span>Srl<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;104.8px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png&#8221; title_text=&#8221;Tracciato 23521&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; transform_scale=&#8221;90%|90%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]Matricule : VR904<br \/>\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png&#8221; title_text=&#8221;Tracciato 23514&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; link_option_url=&#8221;mailto:goitese@latteriagoitese.it&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"mailto:caseificioprabianovr904@gmail.com\">caseificioprabianovr904@gmail.com<\/a><br \/>\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png&#8221; title_text=&#8221;Raggruppa 814&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]T: 045 9619026<\/p>\n<div class=\"span6\">\n<div id=\"ctl00_ContentPlaceHolder8_ctl07_mainDiv\" class=\"map-consorziati\">\n<div id=\"8e4175d3af7e4b1abf170ee25ea536fe\" class=\"map\">\n<div>\n<div class=\"gm-style\">\n<div role=\"region\" aria-label=\"Mappa\" aria-describedby=\"E26FB0D6-3062-4B22-BFEF-383203B21D23\">\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png&#8221; title_text=&#8221;Raggruppa 818&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"p1\">Via Casa Punta, 3<br \/>\n37069 &#8211; Villafranca (VR)<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;32px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|auto|0px|auto|false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;FontPadano-Bold|300|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;24px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; text_orientation=&#8221;center&#8221; width=&#8221;30%&#8221; width_tablet=&#8221;50%&#8221; width_phone=&#8221;auto&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||35px||false|false&#8221; custom_padding=&#8221;2px|20px|20px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}&#8221;]<\/p>\n<div class=\"related_tax\"><span style=\"font-size: medium;\">Caseificio di Prabiano di Renofio Enrico Erminio e figlio <span>Srl<\/span><\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;map_with_content_sec&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;0px|auto|0px|auto|false|false&#8221; custom_padding=&#8221;0px||0px|||&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_all=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; module_class=&#8221;gp_new_map_text&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_text=&#8221;Lorem Ipsum&#8221; module_class=&#8221;mobile_btn&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;26px&#8221; button_text_color=&#8221;#0f0f0f&#8221; button_bg_color=&#8221;#ffdc00&#8243; button_border_color=&#8221;#ffdc00&#8243; button_border_radius=&#8221;48px&#8221; button_font=&#8221;FontPadano-Bold|700|||||||&#8221; button_use_icon=&#8221;off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_code _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"map\" data-lat=\"45.3694168\" data-lng=\"10.8255435\"  style=\"height:400px\" \n                    data-title=\"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl\"\n                    data-address=\"Via Casa Punta, 3 37069 - Villafranca (VR)\" \n                    data-tel=\"045\/9619026\" \n                    data-email=\"caseificioprabianovr904@gmail.com\" \n                    data-fax=\"\" \n                    data-website=\"\">\n                  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VR904 \/n Ville : Villafranca (VR)<\/p>\n","protected":false},"featured_media":151950,"parent":0,"menu_order":693,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" fullwidth=\"on\" _builder_version=\"4.19.2\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_fullwidth_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/testata-consorz.jpg\" title_text=\"testata-consorz\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"||||false|false\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_code _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][custom_breadcrumbs][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" specialty=\"on\" module_class=\"consortium_main_section\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"1_2\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_text _builder_version=\"4.19.4\" _module_preset=\"default\" header_font=\"Merriweather|700|||||||\" header_text_color=\"#221f1c\" header_font_size=\"80px\" hover_enabled=\"0\" global_colors_info=\"{}\" header_line_height=\"70px\" sticky_enabled=\"0\"]\r\n<h1 style=\"text-align: center\">LATTERIA COOPERATIVA GOITESE SOCIET\u00c0 AGRICOLA COOP.VA 21<\/h1>\r\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_2\" specialty_columns=\"2\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" min_height=\"104.8px\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png\" title_text=\"Tracciato 23521\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\r\n\r\nMatricola: MN461\r\n\r\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png\" title_text=\"Tracciato 23514\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\r\n\r\ngoitese@latteriagoitese.it\r\n\r\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png\" title_text=\"Raggruppa 814\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\r\n\r\nT: 0376 686940 | F: 0376 605995\r\n\r\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png\" title_text=\"Raggruppa 818\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\r\n\r\nVia Torre, 81\/A 46044 - Goito (MN)\r\n\r\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-816.png\" title_text=\"Raggruppa 816\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\r\n\r\nlatteriagoitese.it <img src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" width=\"undefined\" height=\"undefined\" alt=\"\" class=\"wp-image-1443 alignnone size-full\">\r\n\r\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"map_with_content_sec\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#f7f7f7\" custom_padding=\"91px||74px||false|false\" global_colors_info=\"{}\"][et_pb_row column_structure=\"1_3,2_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" custom_padding=\"3px|||||\" global_colors_info=\"{}\"][et_pb_column type=\"1_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_button button_text=\"Lorem Ipsum\" _builder_version=\"4.19.4\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" hover_enabled=\"0\" global_colors_info=\"{}\" locked=\"off\" module_class=\"mobile_btn\" sticky_enabled=\"0\"][\/et_pb_button][et_pb_code _builder_version=\"4.19.3\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"]\r\n<div style=\"width: 100%\"><iframe width=\"395\" height=\"395\" frameborder=\"0\" src=\"https:\/\/maps.google.com\/maps?width=395&height=395&hl=en&q=Luna%20Farm+()&t=&z=14&ie=UTF8&iwloc=B&output=embed\"><a href=\"https:\/\/www.maps.ie\/distance-area-calculator.html\">measure distance on map<\/a><\/iframe><\/div>\r\n[\/et_pb_code][\/et_pb_column][et_pb_column type=\"2_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_button button_text=\"Lorem Ipsum\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" text_line_height=\"31px\" global_colors_info=\"{}\"]\r\n\r\nOggi siamo nella campagna vicino a Goito, in provincia di Mantova, alla Latteria Goitese dove fervono i preparativi per i festeggiamenti del 50\u00b0 anniversario.\r\n\r\nL\u2019idea \u00e8 quella di fare una messa con tutti i soci e gli amici della latteria, una benedizione ai locali e poi una cena, sempre in caseificio. Un grande traguardo, fatto del sacrificio di tante persone che per\u00f2 \u00e8 anche una grande soddisfazione: oggi il Caseificio continua a lavorare molto bene ed ha grandi progetti di ampliamento.\r\n\r\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" custom_padding=\"||4px|||\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" text_line_height=\"31px\" global_colors_info=\"{}\"]\r\n\r\nMassimo Dalzini \u00e8 orgoglioso di essere presidente di questa realt\u00e0 e felice di constatare che le nuove generazioni vogliono portare avanti il lavoro in caseificio.\r\n\u201cNon \u00e8 cos\u00ec scontato, \u00e8 un lavoro duro. Sia per la parte produttiva ma anche per tutto quello che riguarda il lavoro dei campi e nelle stalle\u201d\r\n\r\nAl momento la produzione \u00e8 di 134 forme di Grana Padano al giorno ma l\u2019idea \u00e8 di aumentare nel prossimo periodo, per questo sono iniziati i lavori di costruzione di un nuovo magazzino di stagionatura e da pochi anni \u00e8 stata costruita una nuova salina con capienza pi\u00f9 elevata. Per tutti questi lavori si \u00e8 guardato a nuove tecnologie e al risparmio energetico.\r\n\r\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"consortium_msin_slider\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"62px||62px||false|false\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][ba_image_carousel animation_speed=\"400ms\" is_autoplay=\"off\" slide_count=\"4\" nav_icon_size=\"50px\" nav_color=\"#000000\" nav_bg=\"RGBA(255,255,255,0)\" nav_pos_x=\"-50px\" slide_count_tablet=\"2\" slide_count_phone=\"1\" slide_count_last_edited=\"on|tablet\" _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"100%\" custom_padding=\"0px||0px|||\" global_colors_info=\"{}\"][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/98ac641fe1d808c.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fe2a2413c646a32.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/b71d2e3d4117b4f.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/72c0e44d7d9e466.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/Crocchettedipatatepisellieprosciuttocop-46647.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][\/ba_image_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"consortium_pagination\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_row column_structure=\"1_2,1_2\" use_custom_gutter=\"on\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_image=\"off\" width=\"100%\" max_width=\"100%\" custom_margin=\"||||false|false\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_color=\"off\" background_image=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/8.1-Schermata-2022-10-18-alle-16.03.07.jpg\" custom_padding=\"30px||30px||false|false\" global_colors_info=\"{}\"][et_pb_button button_text=\"Consorzio Precedente\" button_alignment=\"center\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_post_nav in_same_term=\"off\" show_next=\"off\" prev_text=\"Latteria casaticese societa\u2019 agricola coop.va\" _builder_version=\"4.19.3\" _module_preset=\"default\" title_font=\"Merriweather||||||||\" title_text_color=\"#FFFFFF\" title_font_size=\"60px\" title_line_height=\"60px\" background_enable_color=\"off\" width=\"90%\" module_alignment=\"center\" global_colors_info=\"{}\" prev_text__hover_enabled=\"off|desktop\"][\/et_pb_post_nav][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_color=\"off\" background_image=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/Group-754.png\" custom_padding=\"30px||30px||false|false\" global_colors_info=\"{}\"][et_pb_button button_text=\"Consorzio Successivo\" button_alignment=\"center\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_post_nav show_prev=\"off\" next_text=\"Latteria padana di borgoforte soc. agr. coop.va\" _builder_version=\"4.19.3\" _module_preset=\"default\" title_font=\"Merriweather||||||||\" title_text_color=\"#FFFFFF\" title_font_size=\"60px\" title_line_height=\"60px\" background_enable_color=\"off\" width=\"90%\" module_alignment=\"center\" global_colors_info=\"{}\"][\/et_pb_post_nav][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":""},"consortium_region":[75],"tipologia":[3046,3040,3043],"provincia":[3061],"servizi_online":[],"altro":[],"class_list":["post-82116","consortium","type-consortium","status-publish","has-post-thumbnail","hentry","tipologia-fromageries-avec-magasin-fr-fr","tipologia-producteurs-fr-fr","tipologia-affineurs-fr-fr","provincia-verona-fr-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl - Grana Padano<\/title>\n<meta name=\"description\" content=\"Matricule : VR904 Ville : Villafranca (VR)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Snc\" \/>\n<meta property=\"og:description\" content=\"Matricule : VR904 Ville : Villafranca (VR)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T15:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Logo_Prabiano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\\\/\",\"name\":\"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"datePublished\":\"2023-02-13T14:11:59+00:00\",\"dateModified\":\"2026-01-13T15:52:12+00:00\",\"description\":\"Matricule : VR904 Ville : Villafranca (VR)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#breadcrumb\"},\"inLanguage\":\"fr-fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-fr\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"width\":511,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/le-consortium-de-protection\\\/les-protagonistes-les-membres-du-consortium\\\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/fr-fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-fr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl - Grana Padano","description":"Matricule : VR904 Ville : Villafranca (VR)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/","og_locale":"fr_FR","og_type":"article","og_title":"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Snc","og_description":"Matricule : VR904 Ville : Villafranca (VR)","og_url":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/","og_site_name":"Grana Padano","article_modified_time":"2026-01-13T15:52:12+00:00","og_image":[{"width":517,"height":311,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Logo_Prabiano.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/","url":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/","name":"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/fr-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","datePublished":"2023-02-13T14:11:59+00:00","dateModified":"2026-01-13T15:52:12+00:00","description":"Matricule : VR904 Ville : Villafranca (VR)","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#breadcrumb"},"inLanguage":"fr-fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-fr","@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","width":511,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/fr-fr\/le-consortium-de-protection\/les-protagonistes-les-membres-du-consortium\/caseificio-di-prabiano-di-renofio-enrico-erminio-e-figlio-snc#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/fr-fr\/"},{"@type":"ListItem","position":2,"name":"Caseificio di Prabiano di Renofio Enrico Erminio e figlio Srl"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/fr-fr\/#website","url":"https:\/\/www.granapadano.it\/fr-fr\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/fr-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-fr"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/consortium\/82116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/consortium"}],"about":[{"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/types\/consortium"}],"version-history":[{"count":6,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/consortium\/82116\/revisions"}],"predecessor-version":[{"id":144669,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/consortium\/82116\/revisions\/144669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/media\/151950"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/media?parent=82116"}],"wp:term":[{"taxonomy":"consortium_region","embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/consortium_region?post=82116"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/tipologia?post=82116"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/provincia?post=82116"},{"taxonomy":"servizi_online","embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/servizi_online?post=82116"},{"taxonomy":"altro","embeddable":true,"href":"https:\/\/www.granapadano.it\/fr-fr\/wp-json\/wp\/v2\/altro?post=82116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}