{"id":85874,"date":"2023-02-17T16:42:32","date_gmt":"2023-02-17T16:42:32","guid":{"rendered":"https:\/\/www.granapadano.it\/consortium\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/"},"modified":"2023-04-07T10:20:06","modified_gmt":"2023-04-07T10:20:06","slug":"biocaseificio-tomasoni-di-tomasoni-massimo-c-snc","status":"publish","type":"consortium","link":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/","title":{"rendered":"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_code _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_section global_module=\"17795 \"][\/et_pb_section][\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbproduction_sub_hub_main_wrapper\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb13px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_class=\u00bbrecipe_filter_section\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_padding=\u00bb||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/es\/\">Inicio<\/a>  <  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_class=\u00bbconsortium_main_section\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbMerriweather|700|||||||\u00bb header_text_color=\u00bb#221f1c\u00bb header_font_size=\u00bb44px\u00bb header_line_height=\u00bb52px\u00bb width=\u00bb96.7%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span>Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. SNC<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb104.8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png\u00bb title_text=\u00bbTracciato 23521&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; transform_scale=\u00bb90%|90%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Matr\u00edcula: BS603<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png\u00bb title_text=\u00bbTracciato 23514&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url=\u00bbmailto:goitese@latteriagoitese.it\u00bb global_colors_info=\u00bb{}\u00bb]<span style=\"color: #000000;\"><a href=\"mailto:info@biocaseificiotomasoni.it\" title=\"info@biocaseificiotomasoni.it\" style=\"color: #000000;\" target=\"_blank\" rel=\"noopener\">info@biocaseificiotomasoni.it<\/a><\/span>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png\u00bb title_text=\u00bbRaggruppa 814&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>T: <span>030 951007<\/span>| F: <span>030 9518147<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png\u00bb title_text=\u00bbRaggruppa 818&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p class=\"p1\"><span>Via Roma, 30<\/span><br \/><span>25023 &#8211; Gottolengo (BS)<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-816.png\u00bb title_text=\u00bbRaggruppa 816&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url_new_window=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: #000000;\"><a href=\"http:\/\/www.biocaseificiotomasoni.it\" target=\"_blank\" rel=\"noopener\" style=\"color: #000000;\">biocaseificiotomasoni.it<\/a><\/span> <img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" width=\"undefined\" height=\"undefined\" alt=\"\" class=\"wp-image-1443 alignnone size-full\"><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Icon-Acquista-online-3.png\u00bb title_text=\u00bbIcon-Acquista online\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url=\u00bbhttps:\/\/www.biologicamenteshop.it\/\u00bb link_option_url_new_window=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: #000000;\">Compra en l\u00ednea a la queser\u00eda<\/span> <img decoding=\"async\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" width=\"undefined\" height=\"undefined\" alt=\"\" class=\"wp-image-1443 alignnone size-full\"><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbmap_with_content_sec\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; custom_padding=\u00bb60px||40px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_padding=\u00bb3px||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; module_id=\u00bbgp_new_map_text\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_text=\u00bbLorem Ipsum\u00bb module_class=\u00bbmobile_btn\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb26px\u00bb button_text_color=\u00bb#0f0f0f\u00bb button_bg_color=\u00bb#ffdc00&#8243; button_border_color=\u00bb#ffdc00&#8243; button_border_radius=\u00bb48px\u00bb button_font=\u00bbFontPadano-Bold|700|||||||\u00bb button_use_icon=\u00bboff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_code _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div id=\"map\" data-lat=\"45.2888727\" data-lng=\"10.2672514\"  style=\"height:400px\" \n                    data-title=\"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc\"\n                    data-address=\"Via Roma, 30 25023 - Gottolengo (BS)\" \n                    data-tel=\"030 951007\" \n                    data-email=\"info@biocaseificiotomasoni.it\" \n                    data-fax=\"030 9518147\" \n                    data-website=\"https:\/\/www.biocaseificiotomasoni.it\">\n                  <\/div>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbFontPadano-Bold|300|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb24px\u00bb background_color=\u00bbgcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d\u00bb text_orientation=\u00bbcenter\u00bb width=\u00bb55.1%\u00bb width_tablet=\u00bb50%\u00bb width_phone=\u00bbauto\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||35px||false|false\u00bb custom_padding=\u00bb2px|20px|20px|20px|false|false\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}\u00bb]<\/p>\n<div class=\"related_tax\"><span style=\"font-size: medium;\">Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. SNC<\/span><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMerriweather|300|||||||\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb26px\u00bb width=\u00bb98%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Entrando en un peque\u00f1a callejuela en Gottolengo, Brescia, llegamos a la queser\u00eda Tomasoni en su ducent\u00e9simo primer a\u00f1o de vida.<\/p>\n<p><strong><em>\u201cS\u00ed, 201 a\u00f1os de la creaci\u00f3n, que tuvo lugar gracias a la sabidur\u00eda del bisabuelo Angelo. Actividad que continu\u00f3 despu\u00e9s mi abuelo Bortolo y mi padre Ottorino\u201d.<\/em><\/strong><span><\/span><\/p>\n<p><span>Es Massimo quien nos cuenta la historia de su queser\u00eda.<\/span><\/p>\n<p><span>Hoy d\u00eda lleva adelante el negocio con toda la familia: madre, padre, los hermanos Alberto y Stefano, y este \u00faltimo es el quesero.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; module_class=\u00bbarticle_sub_img_text_content\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb94%\u00bb custom_margin=\u00bb|auto|0px|auto|false|false\u00bb custom_padding=\u00bb||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; module_class=\u00bbarticle_sub_img_wrap\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/bs603-21347.jpg\u00bb title_text=\u00bbbs603-21347&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; module_class=\u00bbarticle_sub_text_wrap\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMerriweather|300|||||||\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb26px\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><em>\u201cImaginaos que el abuelo tiene 75 a\u00f1os pero todas las ma\u00f1anas a las 4 ya est\u00e1 aqu\u00ed manos a la obra, \u00a1es de veras un pesado pero no podr\u00edamos prescindir de \u00e9l!<\/em><\/strong><\/p>\n<p>Su peque\u00f1a actividad produce Grana Padano desde los a\u00f1os 50, cuatro ruedas al d\u00eda aproximadamente. <\/p>\n<p>Adem\u00e1s de la marca Grana Padano, han decidido emprender el camino de los productos ecol\u00f3gicos, solicitando por tanto una certificaci\u00f3n adicional al organismo responsable, ICEA Lombard\u00eda. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; module_class=\u00bbarticle_sub_img_text_content_left\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb94%\u00bb custom_padding=\u00bb||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; module_class=\u00bbarticle_sub_img_wrap_left\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/bs6035-21352-38377.jpg\u00bb title_text=\u00bbbs6035-21352-38377&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||7px|||\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; module_class=\u00bbarticle_sub_text_wrap_left\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMerriweather|300|||||||\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb26px\u00bb width=\u00bb99%\u00bb custom_margin=\u00bb|||18px||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Los productos que hacen son: Grana Padano, pero tambi\u00e9n robiola, crescenza, mozzarella, yogur, ricotta&#8230; se venden en la tienda, h\u00e1bilmente administrada por su madre, pero sobre todo se venden a los Grupos de Compra Solidaria situados principalmente en la zona de Mil\u00e1n.<\/p>\n<p>Comenzaron con unos pocos grupos, pero despu\u00e9s gracias a la transmisi\u00f3n de boca en boca, el c\u00edrculo se ha ido ampliando.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; module_class=\u00bbarticle_sub_img_text_content\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb94%\u00bb custom_margin=\u00bb|auto|4px|auto||\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; module_class=\u00bbarticle_sub_img_wrap\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/bs6036-21353-38378.jpg\u00bb title_text=\u00bbbs6036-21353-38378&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; module_class=\u00bbarticle_sub_text_wrap\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMerriweather|300|||||||\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb26px\u00bb width=\u00bb98%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"background-color: #f7f7f7; font-size: 18px;\">Organizan frecuentemente visitas guiadas para los clientes porque desean mostrar c\u00f3mo se produce su queso.<\/span><\/p>\n<p>Est\u00e1n orgullosos de su trabajo y esperan poder mantenerlo vivo e inalterado durante muchos a\u00f1os a\u00fan. Aqu\u00ed todav\u00eda se pueden ver las \u00abcubetas\u00bb donde la nata aflora a la superficie y las tinas en las que las ruedas est\u00e1n sumergidas en agua y sal.<\/p>\n<p>\u00a1Gracias a la familia Tomasoni por el tiempo dedicado y la pasi\u00f3n transmitida!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbImage Carousel\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; global_colors_info=\u00bb%91%93&#8243;][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb module_class=\u00bbimg_carousel_main\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbimage-magnify\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/03\/Tomasoni-1-g.jpg\u00bb title_text=\u00bb\u00bb show_in_lightbox=\u00bbon\u00bb show_bottom_space=\u00bboff\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb module_class=\u00bbpop-hover-1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/03\/Tomasoni-2-g.jpg\u00bb title_text=\u00bb\u00bb show_in_lightbox=\u00bbon\u00bb show_bottom_space=\u00bboff\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb module_class=\u00bbpop-hover-1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/03\/Tomasoni-3-g.jpg\u00bb title_text=\u00bb\u00bb show_in_lightbox=\u00bbon\u00bb show_bottom_space=\u00bboff\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb module_class=\u00bbpop-hover-1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/03\/Tomasoni-4-g.jpg\u00bb title_text=\u00bb\u00bb show_in_lightbox=\u00bbon\u00bb show_bottom_space=\u00bboff\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb module_class=\u00bbpop-hover-1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbCSS &#038; JS CODE IMAGE POPUP CAROUSEL   : 01&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bb JS CODE\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/slick-carousel\/1.6.0\/slick.js\"><\/script><!-- [et_pb_line_break_holder] --><script>jQuery(function(s){s(\".image-magnify\").slick({slidesToShow:4,slidesToScroll:1,autoplaySpeed:700,arrows:!0,dots:false,responsive:[{breakpoint:981,settings:{slidesToShow:2,slidesToScroll:1}},{breakpoint:766,settings:{slidesToShow:1,slidesToScroll:1}}]})});<\/script><!-- [et_pb_line_break_holder] -->[\/et_pb_code][et_pb_code admin_label=\u00bbCSS CODE\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] --> .pop-hover-1 {<!-- [et_pb_line_break_holder] -->  overflow: hidden;<!-- [et_pb_line_break_holder] -->  padding: 5px;<!-- [et_pb_line_break_holder] -->  position: relative;<!-- [et_pb_line_break_holder] -->  transform: scale(0.9) !important;<!-- [et_pb_line_break_holder] --> transition: all 0.3s;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->.pop-hover-1:hover .et_pb_lightbox_image:before,<!-- [et_pb_line_break_holder] -->.pop-hover-1:hover .et_pb_lightbox_image:after {<!-- [et_pb_line_break_holder] -->  opacity: 1;<!-- [et_pb_line_break_holder] -->  transform: scale(1);<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->.pop-hover-1 .et_pb_lightbox_image .et_pb_image_wrap {<!-- [et_pb_line_break_holder] -->  overflow: hidden;<!-- [et_pb_line_break_holder] -->  border-radius: 20px;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->.pop-hover-1:hover{<!-- [et_pb_line_break_holder] -->   transform: scale(1) !important;<!-- [et_pb_line_break_holder] -->  transition: all 0.3s;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.pop-hover-1 .et_pb_lightbox_image .et_pb_image_wrap img {<!-- [et_pb_line_break_holder] -->  width: 100%;<!-- [et_pb_line_break_holder] -->  height: auto;<!-- [et_pb_line_break_holder] -->  transition: all 0.3s ease-in-out;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.pop-hover-1:hover .et_pb_lightbox_image .et_pb_image_wrap .et_overlay {<!-- [et_pb_line_break_holder] -->  opacity: 1;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->.pop-hover-1 .et_pb_lightbox_image .et_pb_image_wrap .et_overlay:before {<!-- [et_pb_line_break_holder] -->  display: inline-block;<!-- [et_pb_line_break_holder] -->  width: 65px;<!-- [et_pb_line_break_holder] -->  height: 65px;<!-- [et_pb_line_break_holder] -->  line-height: 65px;<!-- [et_pb_line_break_holder] -->  border-radius: 50%;<!-- [et_pb_line_break_holder] -->  background: #fff;<!-- [et_pb_line_break_holder] -->  color: #333;<!-- [et_pb_line_break_holder] -->  top: 60%;<!-- [et_pb_line_break_holder] -->  font-size: 30px;<!-- [et_pb_line_break_holder] -->  transition: all 0.6s ease 0s;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .img_carousel_main button.slick-prev,.img_carousel_main button.slick-next{<!-- [et_pb_line_break_holder] -->     top: 43% !important;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->  .img_carousel_main button.slick-prev.slick-arrow:before {<!-- [et_pb_line_break_holder] -->    \/*content: \"34\";*\/<!-- [et_pb_line_break_holder] -->    position: relative;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->  .img_carousel_main .slick-prev {<!-- [et_pb_line_break_holder] -->      left: -45px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->  .img_carousel_main button.slick-arrow:before{<!-- [et_pb_line_break_holder] -->   color: #000000;<!-- [et_pb_line_break_holder] -->    font-size: 51px;<!-- [et_pb_line_break_holder] -->    text-shadow: 0 0;<!-- [et_pb_line_break_holder] -->    font-family: ETmodules !important;<!-- [et_pb_line_break_holder] -->    font-weight: 400;<!-- [et_pb_line_break_holder] -->    font-style: normal;<!-- [et_pb_line_break_holder] -->    font-variant: normal;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->  .img_carousel_main button.slick-next.slick-arrow:before {<!-- [et_pb_line_break_holder] -->    \/*content: \"35\";*\/<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .img_carousel_main img{<!-- [et_pb_line_break_holder] -->    height: 284px !important;<!-- [et_pb_line_break_holder] -->    object-fit: cover !important;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BS603 \/n Ciudad: Gottolengo (BS)<\/p>\n","protected":false},"featured_media":151942,"parent":0,"menu_order":36,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"consortium_region":[73],"tipologia":[3045,3048,3051,3042],"provincia":[3059],"servizi_online":[3064],"altro":[3092],"class_list":["post-85874","consortium","type-consortium","status-publish","has-post-thumbnail","hentry","tipologia-maduradores-es","tipologia-queserias-con-tienda-es","tipologia-exportadores-es","tipologia-productores-es","provincia-brescia-es","servizi_online-comercio-electronico-consorciados","altro-el-verdadero-sabor-de-italia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc - Grana Padano<\/title>\n<meta name=\"description\" content=\"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc\" \/>\n<meta property=\"og:description\" content=\"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-07T10:20:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/\",\"name\":\"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"datePublished\":\"2023-02-17T16:42:32+00:00\",\"dateModified\":\"2023-04-07T10:20:06+00:00\",\"description\":\"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"width\":511,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc - Grana Padano","description":"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/","og_locale":"es_ES","og_type":"article","og_title":"Biocaseificio Tomasoni di Tomasoni Massimo & C. snc","og_description":"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)","og_url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/","og_site_name":"Grana Padano","article_modified_time":"2023-04-07T10:20:06+00:00","og_image":[{"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/","url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/","name":"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","datePublished":"2023-02-17T16:42:32+00:00","dateModified":"2023-04-07T10:20:06+00:00","description":"Matr\u00edcula: BS603 Ciudad: Gottolengo (BS)","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","width":511,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/biocaseificio-tomasoni-di-tomasoni-massimo-c-snc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/es\/"},{"@type":"ListItem","position":2,"name":"Biocaseificio Tomasoni di Tomasoni Massimo &amp; C. snc"}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/es\/#website","url":"https:\/\/www.granapadano.it\/es\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/85874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium"}],"about":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/types\/consortium"}],"version-history":[{"count":5,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/85874\/revisions"}],"predecessor-version":[{"id":86058,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/85874\/revisions\/86058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media\/151942"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media?parent=85874"}],"wp:term":[{"taxonomy":"consortium_region","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium_region?post=85874"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/tipologia?post=85874"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/provincia?post=85874"},{"taxonomy":"servizi_online","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/servizi_online?post=85874"},{"taxonomy":"altro","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/altro?post=85874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}