{"id":83239,"date":"2023-02-13T10:18:46","date_gmt":"2023-02-13T10:18:46","guid":{"rendered":"https:\/\/www.granapadano.it\/consortium\/cas-soc-comprensoriale-di-primiero-s-c-a\/"},"modified":"2023-05-19T10:17:36","modified_gmt":"2023-05-19T10:17:36","slug":"cas-soc-comprensoriale-di-primiero-s-c-a","status":"publish","type":"consortium","link":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/","title":{"rendered":"Cas. Soc. Comprensoriale di Primiero S.C.A."},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_code _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_section global_module=\"17795 \"][\/et_pb_section][\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbproduction_sub_hub_main_wrapper\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb13px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_class=\u00bbrecipe_filter_section\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_padding=\u00bb||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/es\/\">Inicio<\/a>  <  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_class=\u00bbconsortium_main_section\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbMerriweather|700|||||||\u00bb header_text_color=\u00bb#221f1c\u00bb header_font_size=\u00bb44px\u00bb header_line_height=\u00bb52px\u00bb width=\u00bb96.7%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Cas. Soc. Comprensoriale di Primiero S.C.A.<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb104.8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png\u00bb title_text=\u00bbTracciato 23521&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; transform_scale=\u00bb90%|90%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Matr\u00edcula: TN310<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png\u00bb title_text=\u00bbTracciato 23514&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url=\u00bbmailto:goitese@latteriagoitese.it\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><a href=\"mailto:info@caseificioprimiero.com\">info@caseificioprimiero.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png\u00bb title_text=\u00bbRaggruppa 814&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>T: 0439 62941<\/p>\n<div class=\"span6\">\n<div id=\"ctl00_ContentPlaceHolder8_ctl07_mainDiv\" class=\"map-consorziati\">\n<div id=\"8e4175d3af7e4b1abf170ee25ea536fe\" class=\"map\">\n<div>\n<div class=\"gm-style\">\n<div role=\"region\" aria-label=\"Mappa\" aria-describedby=\"E26FB0D6-3062-4B22-BFEF-383203B21D23\">\n<div>\n<div>\n<div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png\u00bb title_text=\u00bbRaggruppa 818&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p class=\"p1\">Via Roma, 179<br \/>38050 &#8211; Mezzano di Primiero (TN)<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-816.png\u00bb title_text=\u00bbRaggruppa 816&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.caseificioprimiero.com\/chi-siamo\/caseificio\" target=\"_blank\" rel=\"noopener\">caseificioprimiero.com<\/a><\/span> <img decoding=\"async\" class=\"wp-image-1443 alignnone size-full\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" alt=\"\" width=\"undefined\" height=\"undefined\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2023\/02\/Icon-Acquista-online-3.png\u00bb title_text=\u00bbIcon-Acquista online\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url=\u00bbhttps:\/\/www.biologicamenteshop.it\/\u00bb link_option_url_new_window=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><a href=\"https:\/\/www.caseificioprimiero.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000;\">Compra en l\u00ednea a la queser\u00eda<\/span><\/a> <img decoding=\"async\" class=\"wp-image-1443 alignnone size-full\" src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" alt=\"\" width=\"undefined\" height=\"undefined\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; custom_padding=\u00bb32px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-33px|auto|-29px|auto||\u00bb custom_padding=\u00bb24px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbFontPadano-Bold|300|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb24px\u00bb background_color=\u00bbgcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d\u00bb text_orientation=\u00bbcenter\u00bb width=\u00bb29.4%\u00bb width_tablet=\u00bb50%\u00bb width_phone=\u00bbauto\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||30px||false|false\u00bb custom_padding=\u00bb2px|20px|20px|20px|false|false\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb global_colors_info=\u00bb{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}\u00bb]<\/p>\n<div class=\"related_tax\"><span style=\"font-size: medium;\">Cas. Soc. Comprensoriale di Primiero S.C.A.<\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbmap_with_content_sec\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_class=\u00bbgp_new_map_text \u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_margin=\u00bb0px|auto|0px|auto|false|false\u00bb custom_padding=\u00bb0px||0px|||\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_text=\u00bbLorem Ipsum\u00bb module_class=\u00bbmobile_btn\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb26px\u00bb button_text_color=\u00bb#0f0f0f\u00bb button_bg_color=\u00bb#ffdc00&#8243; button_border_color=\u00bb#ffdc00&#8243; button_border_radius=\u00bb48px\u00bb button_font=\u00bbFontPadano-Bold|700|||||||\u00bb button_use_icon=\u00bboff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_code _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div id=\"map\" data-lat=\"46.1557363\" data-lng=\"11.8136222\"  style=\"height:400px\" \n                    data-title=\"Cas. Soc. Comprensoriale di Primiero S.C.A.\"\n                    data-address=\"Via Roma, 179 38050 - Mezzano di Primiero (TN)\" \n                    data-tel=\"0439 62941\" \n                    data-email=\"info@caseificioprimiero.com\" \n                    data-fax=\"\" \n                    data-website=\"https:\/\/www.caseificioprimiero.com\/chi-siamo\/caseificio\">\n                  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TN310 \/n Ciudad: Mezzano di Primiero (TN)<\/p>\n","protected":false},"featured_media":151952,"parent":0,"menu_order":532,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"consortium_region":[74],"tipologia":[3045,3048,3042],"provincia":[3110],"servizi_online":[3064],"altro":[],"class_list":["post-83239","consortium","type-consortium","status-publish","has-post-thumbnail","hentry","tipologia-maduradores-es","tipologia-queserias-con-tienda-es","tipologia-productores-es","provincia-trento-es","servizi_online-comercio-electronico-consorciados"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cas. Soc. Comprensoriale di Primiero S.C.A. - Grana Padano<\/title>\n<meta name=\"description\" content=\"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cas. Soc. Comprensoriale di Primiero S.C.A.\" \/>\n<meta property=\"og:description\" content=\"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T10:17:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Logo_Primiero.png\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/\",\"name\":\"Cas. Soc. Comprensoriale di Primiero S.C.A. - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"datePublished\":\"2023-02-13T10:18:46+00:00\",\"dateModified\":\"2023-05-19T10:17:36+00:00\",\"description\":\"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4.png\",\"width\":511,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/cas-soc-comprensoriale-di-primiero-s-c-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cas. Soc. Comprensoriale di Primiero S.C.A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cas. Soc. Comprensoriale di Primiero S.C.A. - Grana Padano","description":"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/","og_locale":"es_ES","og_type":"article","og_title":"Cas. Soc. Comprensoriale di Primiero S.C.A.","og_description":"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)","og_url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/","og_site_name":"Grana Padano","article_modified_time":"2023-05-19T10:17:36+00:00","og_image":[{"width":517,"height":311,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/Logo_Primiero.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/","url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/","name":"Cas. Soc. Comprensoriale di Primiero S.C.A. - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","datePublished":"2023-02-13T10:18:46+00:00","dateModified":"2023-05-19T10:17:36+00:00","description":"Matr\u00edcula: TN310 Ciudad: Mezzano di Primiero (TN)","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/4.png","width":511,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/cas-soc-comprensoriale-di-primiero-s-c-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/es\/"},{"@type":"ListItem","position":2,"name":"Cas. Soc. Comprensoriale di Primiero S.C.A."}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/es\/#website","url":"https:\/\/www.granapadano.it\/es\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/83239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium"}],"about":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/types\/consortium"}],"version-history":[{"count":4,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/83239\/revisions"}],"predecessor-version":[{"id":100880,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/83239\/revisions\/100880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media\/151952"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media?parent=83239"}],"wp:term":[{"taxonomy":"consortium_region","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium_region?post=83239"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/tipologia?post=83239"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/provincia?post=83239"},{"taxonomy":"servizi_online","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/servizi_online?post=83239"},{"taxonomy":"altro","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/altro?post=83239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}