{"id":82191,"date":"2023-02-13T15:59:46","date_gmt":"2023-02-13T15:59:46","guid":{"rendered":"https:\/\/www.granapadano.it\/consortium\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/"},"modified":"2023-04-05T18:44:17","modified_gmt":"2023-04-05T18:44:17","slug":"caseificio-morandini-sas-di-morandini-walter-morandini-diego-c","status":"publish","type":"consortium","link":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/","title":{"rendered":"Caseificio Morandini SAS di Morandini Walter, Morandini Diego &#038; C."},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_code _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_section global_module=\"17795 \"][\/et_pb_section][\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbproduction_sub_hub_main_wrapper\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb13px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_class=\u00bbrecipe_filter_section\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_padding=\u00bb||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/es\/\">Inicio<\/a>  <  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb module_class=\u00bbconsortium_main_section\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.20.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbMerriweather|700|||||||\u00bb header_text_color=\u00bb#221f1c\u00bb header_font_size=\u00bb44px\u00bb header_line_height=\u00bb52px\u00bb width=\u00bb96.7%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Caseificio Morandini SAS di Morandini Walter, Morandini Diego &amp; c.<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb104.8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png\u00bb title_text=\u00bbTracciato 23521&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; transform_scale=\u00bb90%|90%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]Matr\u00edcula: VR911[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png\u00bb title_text=\u00bbTracciato 23514&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb link_option_url=\u00bbmailto:goitese@latteriagoitese.it\u00bb global_colors_info=\u00bb{}\u00bb]<span style=\"color: #000000;\"><a href=\"mailto:caseificiomorandini@hotmail.com\" target=\"_blank\" rel=\"noopener\" title=\"caseificiomorandini@hotmail.com\" style=\"color: #000000;\">caseificiomorandini@hotmail.com<\/a><\/span>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png\u00bb title_text=\u00bbRaggruppa 814&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb global_colors_info=\u00bb{}\u00bb]T: 045 7075050<\/p>\n<div class=\"span6\">\n<div id=\"ctl00_ContentPlaceHolder8_ctl07_mainDiv\" class=\"map-consorziati\">\n<div id=\"8e4175d3af7e4b1abf170ee25ea536fe\" class=\"map\">\n<div>\n<div class=\"gm-style\">\n<div aria-label=\"Mappa\" role=\"region\" aria-describedby=\"E26FB0D6-3062-4B22-BFEF-383203B21D23\">\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png\u00bb title_text=\u00bbRaggruppa 818&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ffdc00&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.19.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#0f0f0f\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb header_font_size=\u00bb21px\u00bb header_line_height=\u00bb27px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p class=\"p1\">Via Dosso, 1<br \/>\n37020 &#8211; Erbezzo (VR)<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; custom_padding=\u00bb32px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px|auto|0px|auto|false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbFontPadano-Bold|300|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb24px\u00bb background_color=\u00bbgcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d\u00bb text_orientation=\u00bbcenter\u00bb width=\u00bb30%\u00bb width_tablet=\u00bb50%\u00bb width_phone=\u00bbauto\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||35px||false|false\u00bb custom_padding=\u00bb2px|20px|20px|20px|false|false\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}\u00bb]<\/p>\n<div class=\"related_tax\"><span style=\"font-size: medium;\">Caseificio Morandini SAS di Morandini Walter, Morandini Diego &#038; c.<\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbmap_with_content_sec\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f7f7f7&#8243; custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb90%\u00bb custom_margin=\u00bb0px|auto|0px|auto|false|false\u00bb custom_padding=\u00bb0px||0px|||\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; module_class=\u00bbgp_new_map_text\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_text=\u00bbLorem Ipsum\u00bb module_class=\u00bbmobile_btn\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb26px\u00bb button_text_color=\u00bb#0f0f0f\u00bb button_bg_color=\u00bb#ffdc00&#8243; button_border_color=\u00bb#ffdc00&#8243; button_border_radius=\u00bb48px\u00bb button_font=\u00bbFontPadano-Bold|700|||||||\u00bb button_use_icon=\u00bboff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_code _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div id=\"map\" data-lat=\"45.5768736\" data-lng=\"11.0461282\"  style=\"height:400px\" \n                    data-title=\"Caseificio Morandini SAS di Morandini Walter, Morandini Diego &#038; C.\"\n                    data-address=\"Via Dosso, 1 37020 - Erbezzo (VR)\" \n                    data-tel=\"045 7075050\" \n                    data-email=\"caseificiomorandini@hotmail.com\" \n                    data-fax=\"045 7075050\" \n                    data-website=\"\">\n                  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VR911 \/n Ciudad: Erbezzo (VR)<\/p>\n","protected":false},"featured_media":151942,"parent":0,"menu_order":704,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" fullwidth=\"on\" _builder_version=\"4.19.2\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"][et_pb_fullwidth_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/testata-consorz.jpg\" title_text=\"testata-consorz\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"||||false|false\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_code _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][custom_breadcrumbs][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" specialty=\"on\" module_class=\"consortium_main_section\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"1_2\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_text _builder_version=\"4.19.4\" _module_preset=\"default\" header_font=\"Merriweather|700|||||||\" header_text_color=\"#221f1c\" header_font_size=\"80px\" hover_enabled=\"0\" global_colors_info=\"{}\" header_line_height=\"70px\" sticky_enabled=\"0\"]\n<h1 style=\"text-align: center\">LATTERIA COOPERATIVA GOITESE SOCIET\u00c0 AGRICOLA COOP.VA 21<\/h1>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_2\" specialty_columns=\"2\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" min_height=\"104.8px\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png\" title_text=\"Tracciato 23521\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\n\nMatricola: MN461\n\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png\" title_text=\"Tracciato 23514\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\n\ngoitese@latteriagoitese.it\n\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png\" title_text=\"Raggruppa 814\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\n\nT: 0376 686940 | F: 0376 605995\n\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png\" title_text=\"Raggruppa 818\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\n\nVia Torre, 81\/A 46044 - Goito (MN)\n\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\"1_2,1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/Raggruppa-816.png\" title_text=\"Raggruppa 816\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#ffdc00\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\"1_2\" saved_specialty_column_type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" global_colors_info=\"{}\"]\n\nlatteriagoitese.it <img src=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/next.svg\" width=\"undefined\" height=\"undefined\" alt=\"\" class=\"wp-image-1443 alignnone size-full\">\n\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"map_with_content_sec\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_color=\"#f7f7f7\" custom_padding=\"91px||74px||false|false\" global_colors_info=\"{}\"][et_pb_row column_structure=\"1_3,2_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" custom_padding=\"3px|||||\" global_colors_info=\"{}\"][et_pb_column type=\"1_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_button button_text=\"Lorem Ipsum\" _builder_version=\"4.19.4\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" hover_enabled=\"0\" global_colors_info=\"{}\" locked=\"off\" module_class=\"mobile_btn\" sticky_enabled=\"0\"][\/et_pb_button][et_pb_code _builder_version=\"4.19.3\" _module_preset=\"default\" locked=\"off\" global_colors_info=\"{}\"]\n<div style=\"width: 100%\"><iframe width=\"395\" height=\"395\" frameborder=\"0\" src=\"https:\/\/maps.google.com\/maps?width=395&amp;height=395&amp;hl=en&amp;q=Luna%20Farm+()&amp;t=&amp;z=14&amp;ie=UTF8&amp;iwloc=B&amp;output=embed\"><a href=\"https:\/\/www.maps.ie\/distance-area-calculator.html\">measure distance on map<\/a><\/iframe><\/div>\n[\/et_pb_code][\/et_pb_column][et_pb_column type=\"2_3\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_button button_text=\"Lorem Ipsum\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" text_line_height=\"31px\" global_colors_info=\"{}\"]\n\nOggi siamo nella campagna vicino a Goito, in provincia di Mantova, alla Latteria Goitese dove fervono i preparativi per i festeggiamenti del 50\u00b0 anniversario.\n\nL\u2019idea \u00e8 quella di fare una messa con tutti i soci e gli amici della latteria, una benedizione ai locali e poi una cena, sempre in caseificio. Un grande traguardo, fatto del sacrificio di tante persone che per\u00f2 \u00e8 anche una grande soddisfazione: oggi il Caseificio continua a lavorare molto bene ed ha grandi progetti di ampliamento.\n\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" custom_padding=\"||4px|||\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.19.3\" _module_preset=\"default\" text_font=\"Merriweather||||||||\" text_text_color=\"#0f0f0f\" text_font_size=\"26px\" text_line_height=\"31px\" global_colors_info=\"{}\"]\n\nMassimo Dalzini \u00e8 orgoglioso di essere presidente di questa realt\u00e0 e felice di constatare che le nuove generazioni vogliono portare avanti il lavoro in caseificio.\n\u201cNon \u00e8 cos\u00ec scontato, \u00e8 un lavoro duro. Sia per la parte produttiva ma anche per tutto quello che riguarda il lavoro dei campi e nelle stalle\u201d\n\nAl momento la produzione \u00e8 di 134 forme di Grana Padano al giorno ma l\u2019idea \u00e8 di aumentare nel prossimo periodo, per questo sono iniziati i lavori di costruzione di un nuovo magazzino di stagionatura e da pochi anni \u00e8 stata costruita una nuova salina con capienza pi\u00f9 elevata. Per tutti questi lavori si \u00e8 guardato a nuove tecnologie e al risparmio energetico.\n\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"consortium_msin_slider\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"62px||62px||false|false\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"90%\" max_width=\"90%\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][ba_image_carousel animation_speed=\"400ms\" is_autoplay=\"off\" slide_count=\"4\" nav_icon_size=\"50px\" nav_color=\"#000000\" nav_bg=\"RGBA(255,255,255,0)\" nav_pos_x=\"-50px\" slide_count_tablet=\"2\" slide_count_phone=\"1\" slide_count_last_edited=\"on|tablet\" _builder_version=\"4.19.3\" _module_preset=\"default\" width=\"100%\" custom_padding=\"0px||0px|||\" global_colors_info=\"{}\"][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/98ac641fe1d808c.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/fe2a2413c646a32.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/b71d2e3d4117b4f.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/12\/72c0e44d7d9e466.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][ba_image_carousel_child photo=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/Crocchettedipatatepisellieprosciuttocop-46647.png\" _builder_version=\"4.19.3\" _module_preset=\"default\" global_colors_info=\"{}\"][\/ba_image_carousel_child][\/ba_image_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" module_class=\"consortium_pagination\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_row column_structure=\"1_2,1_2\" use_custom_gutter=\"on\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_image=\"off\" width=\"100%\" max_width=\"100%\" custom_margin=\"||||false|false\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_color=\"off\" background_image=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/8.1-Schermata-2022-10-18-alle-16.03.07.jpg\" custom_padding=\"30px||30px||false|false\" global_colors_info=\"{}\"][et_pb_button button_text=\"Consorzio Precedente\" button_alignment=\"center\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_post_nav in_same_term=\"off\" show_next=\"off\" prev_text=\"Latteria casaticese societa\u2019 agricola coop.va\" _builder_version=\"4.19.3\" _module_preset=\"default\" title_font=\"Merriweather||||||||\" title_text_color=\"#FFFFFF\" title_font_size=\"60px\" title_line_height=\"60px\" background_enable_color=\"off\" width=\"90%\" module_alignment=\"center\" global_colors_info=\"{}\" prev_text__hover_enabled=\"off|desktop\"][\/et_pb_post_nav][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.19.3\" _module_preset=\"default\" background_enable_color=\"off\" background_image=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2022\/11\/Group-754.png\" custom_padding=\"30px||30px||false|false\" global_colors_info=\"{}\"][et_pb_button button_text=\"Consorzio Successivo\" button_alignment=\"center\" _builder_version=\"4.19.3\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"26px\" button_text_color=\"#0f0f0f\" button_bg_color=\"#ffdc00\" button_border_color=\"#ffdc00\" button_border_radius=\"48px\" button_font=\"FontPadano-Bold|700|||||||\" button_use_icon=\"off\" global_colors_info=\"{}\"][\/et_pb_button][et_pb_post_nav show_prev=\"off\" next_text=\"Latteria padana di borgoforte soc. agr. coop.va\" _builder_version=\"4.19.3\" _module_preset=\"default\" title_font=\"Merriweather||||||||\" title_text_color=\"#FFFFFF\" title_font_size=\"60px\" title_line_height=\"60px\" background_enable_color=\"off\" width=\"90%\" module_alignment=\"center\" global_colors_info=\"{}\"][\/et_pb_post_nav][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":""},"consortium_region":[75],"tipologia":[3045,3048,3042],"provincia":[3063],"servizi_online":[],"altro":[],"class_list":["post-82191","consortium","type-consortium","status-publish","has-post-thumbnail","hentry","tipologia-maduradores-es","tipologia-queserias-con-tienda-es","tipologia-productores-es","provincia-verona-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caseificio Morandini SAS di Morandini Walter, Morandini Diego &amp; C. - Grana Padano<\/title>\n<meta name=\"description\" content=\"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caseificio Morandini SAS di Morandini Walter, Morandini Diego &amp; C.\" \/>\n<meta property=\"og:description\" content=\"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T18:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/\",\"name\":\"Caseificio Morandini SAS di Morandini Walter, Morandini Diego & C. - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"datePublished\":\"2023-02-13T15:59:46+00:00\",\"dateModified\":\"2023-04-05T18:44:17+00:00\",\"description\":\"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"width\":511,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/el-consorzio-de-proteccion\\\/actores-clave-los-miembros-del-consorcio\\\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caseificio Morandini SAS di Morandini Walter, Morandini Diego &#038; C.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caseificio Morandini SAS di Morandini Walter, Morandini Diego & C. - Grana Padano","description":"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/","og_locale":"es_ES","og_type":"article","og_title":"Caseificio Morandini SAS di Morandini Walter, Morandini Diego & C.","og_description":"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)","og_url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/","og_site_name":"Grana Padano","article_modified_time":"2023-04-05T18:44:17+00:00","og_image":[{"width":511,"height":367,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/","url":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/","name":"Caseificio Morandini SAS di Morandini Walter, Morandini Diego & C. - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","datePublished":"2023-02-13T15:59:46+00:00","dateModified":"2023-04-05T18:44:17+00:00","description":"Matr\u00edcula: VR911 Ciudad: Erbezzo (VR)","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","width":511,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/es\/el-consorzio-de-proteccion\/actores-clave-los-miembros-del-consorcio\/caseificio-morandini-sas-di-morandini-walter-morandini-diego-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/es\/"},{"@type":"ListItem","position":2,"name":"Caseificio Morandini SAS di Morandini Walter, Morandini Diego &#038; C."}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/es\/#website","url":"https:\/\/www.granapadano.it\/es\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/82191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium"}],"about":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/types\/consortium"}],"version-history":[{"count":5,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/82191\/revisions"}],"predecessor-version":[{"id":83953,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium\/82191\/revisions\/83953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media\/151942"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/media?parent=82191"}],"wp:term":[{"taxonomy":"consortium_region","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/consortium_region?post=82191"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/tipologia?post=82191"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/provincia?post=82191"},{"taxonomy":"servizi_online","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/servizi_online?post=82191"},{"taxonomy":"altro","embeddable":true,"href":"https:\/\/www.granapadano.it\/es\/wp-json\/wp\/v2\/altro?post=82191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}