{"id":83475,"date":"2023-02-13T10:34:46","date_gmt":"2023-02-13T10:34:46","guid":{"rendered":"https:\/\/www.granapadano.it\/consortium\/latteria-sociale-di-fondo-s-c-a\/"},"modified":"2023-04-05T19:35:39","modified_gmt":"2023-04-05T19:35:39","slug":"latteria-sociale-di-fondo-s-c-a","status":"publish","type":"consortium","link":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/","title":{"rendered":"Latteria Sociale di Fondo S.C.A."},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_code _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_section global_module=\"17795 \"][\/et_pb_section][\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;production_sub_hub_main_wrapper&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;13px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221;recipe_filter_section&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"breadcrumb\"><a href=\"https:\/\/www.granapadano.it\/de-de\/\">Home<\/a>  <  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; module_class=&#8221;consortium_main_section&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Merriweather|700|||||||&#8221; header_text_color=&#8221;#221f1c&#8221; header_font_size=&#8221;44px&#8221; header_line_height=&#8221;52px&#8221; width=&#8221;96.7%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Latteria Sociale di Fondo S.C.A.<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;104.8px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23521.png&#8221; title_text=&#8221;Tracciato 23521&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; transform_scale=&#8221;90%|90%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]Kenn-Nr.: TN313[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Tracciato-23514.png&#8221; title_text=&#8221;Tracciato 23514&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; link_option_url=&#8221;mailto:goitese@latteriagoitese.it&#8221; global_colors_info=&#8221;{}&#8221;]<span style=\"color: #000000;\"><a href=\"mailto:lat.fondo@virgilio.it\" target=\"_blank\" rel=\"noopener\" title=\"lat.fondo@virgilio.it\" style=\"color: #000000;\">lat.fondo@virgilio.it<\/a><\/span>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-814.png&#8221; title_text=&#8221;Raggruppa 814&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]T: 0463 831294<\/p>\n<div class=\"span6\">\n<div id=\"ctl00_ContentPlaceHolder8_ctl07_mainDiv\" class=\"map-consorziati\">\n<div id=\"8e4175d3af7e4b1abf170ee25ea536fe\" class=\"map\">\n<div>\n<div class=\"gm-style\">\n<div aria-label=\"Mappa\" role=\"region\" aria-describedby=\"E26FB0D6-3062-4B22-BFEF-383203B21D23\">\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.granapadano.it\/wp-content\/uploads\/2022\/12\/Raggruppa-818.png&#8221; title_text=&#8221;Raggruppa 818&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffdc00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#0f0f0f&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;26px&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;27px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"p1\">Via IV Novembre, 70<br \/>38013 &#8211; Fondo (TN)<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;32px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-33px|auto|-29px|auto||&#8221; custom_padding=&#8221;24px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;FontPadano-Bold|300|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;24px&#8221; background_color=&#8221;gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d&#8221; text_orientation=&#8221;center&#8221; width=&#8221;25%&#8221; width_tablet=&#8221;50%&#8221; width_phone=&#8221;auto&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;0px||30px||false|false&#8221; custom_padding=&#8221;2px|20px|20px|20px|false|false&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{%22gcid-26f0371c-74dd-4e63-bbf8-f8ec94f09a6d%22:%91%22background_color%22%93}&#8221;]<\/p>\n<div class=\"related_tax\">Latteria Sociale di Fondo S.C.A.<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;map_with_content_sec&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; custom_margin=&#8221;0px|auto|0px|auto|false|false&#8221; custom_padding=&#8221;0px||0px|||&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_all=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221; module_class=&#8221;gp_new_map_text&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_text=&#8221;Lorem Ipsum&#8221; module_class=&#8221;mobile_btn&#8221; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;26px&#8221; button_text_color=&#8221;#0f0f0f&#8221; button_bg_color=&#8221;#ffdc00&#8243; button_border_color=&#8221;#ffdc00&#8243; button_border_radius=&#8221;48px&#8221; button_font=&#8221;FontPadano-Bold|700|||||||&#8221; button_use_icon=&#8221;off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_code _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<div id=\"map\" data-lat=\"46.4414026\" data-lng=\"11.1301015\"  style=\"height:400px\" \n                    data-title=\"Latteria Sociale di Fondo S.C.A.\"\n                    data-address=\"Via IV Novembre, 70 38013 - Borgo d'Anaunia (TN)\" \n                    data-tel=\"0463 831294\" \n                    data-email=\"lat.fondo@virgilio.it\" \n                    data-fax=\"0463 831294\" \n                    data-website=\"\">\n                  <\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TN313 \/n Stadt: Fondo (TN)<\/p>\n","protected":false},"featured_media":151941,"parent":0,"menu_order":544,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"consortium_region":[74],"tipologia":[3044,3047,3041],"provincia":[3109],"servizi_online":[],"altro":[],"class_list":["post-83475","consortium","type-consortium","status-publish","has-post-thumbnail","hentry","tipologia-reifungsbetriebe-de-de","tipologia-kasereien-mit-verkaufsflache-de-de","tipologia-hersteller-de-de","provincia-trento-de-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Latteria Sociale di Fondo S.C.A. - Grana Padano<\/title>\n<meta name=\"description\" content=\"Kenn-Nr.: TN313 Stadt: Fondo (TN)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Latteria Sociale di Fondo S.C.A.\" \/>\n<meta property=\"og:description\" content=\"Kenn-Nr.: TN313 Stadt: Fondo (TN)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Grana Padano\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T19:35:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/\",\"name\":\"Latteria Sociale di Fondo S.C.A. - Grana Padano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"datePublished\":\"2023-02-13T10:34:46+00:00\",\"dateModified\":\"2023-04-05T19:35:39+00:00\",\"description\":\"Kenn-Nr.: TN313 Stadt: Fondo (TN)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/#breadcrumb\"},\"inLanguage\":\"de-de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-de\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"contentUrl\":\"https:\\\/\\\/granapadano.kleecks-cdn.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5.png\",\"width\":511,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/das-konsortium\\\/i-protagonisti-i-consorziati\\\/latteria-sociale-di-fondo-s-c-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Latteria Sociale di Fondo S.C.A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/\",\"name\":\"Grana Padano\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.granapadano.it\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Latteria Sociale di Fondo S.C.A. - Grana Padano","description":"Kenn-Nr.: TN313 Stadt: Fondo (TN)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/","og_locale":"de_DE","og_type":"article","og_title":"Latteria Sociale di Fondo S.C.A.","og_description":"Kenn-Nr.: TN313 Stadt: Fondo (TN)","og_url":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/","og_site_name":"Grana Padano","article_modified_time":"2023-04-05T19:35:39+00:00","og_image":[{"width":511,"height":367,"url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2023\/02\/thumb-consorziati-5-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/","url":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/","name":"Latteria Sociale di Fondo S.C.A. - Grana Padano","isPartOf":{"@id":"https:\/\/www.granapadano.it\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/#primaryimage"},"image":{"@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/#primaryimage"},"thumbnailUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","datePublished":"2023-02-13T10:34:46+00:00","dateModified":"2023-04-05T19:35:39+00:00","description":"Kenn-Nr.: TN313 Stadt: Fondo (TN)","breadcrumb":{"@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/#breadcrumb"},"inLanguage":"de-de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/"]}]},{"@type":"ImageObject","inLanguage":"de-de","@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/#primaryimage","url":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","contentUrl":"https:\/\/granapadano.kleecks-cdn.com\/wp-content\/uploads\/2025\/01\/5.png","width":511,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/www.granapadano.it\/de-de\/das-konsortium\/i-protagonisti-i-consorziati\/latteria-sociale-di-fondo-s-c-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.granapadano.it\/de-de\/"},{"@type":"ListItem","position":2,"name":"Latteria Sociale di Fondo S.C.A."}]},{"@type":"WebSite","@id":"https:\/\/www.granapadano.it\/de-de\/#website","url":"https:\/\/www.granapadano.it\/de-de\/","name":"Grana Padano","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.granapadano.it\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-de"}]}},"_links":{"self":[{"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/consortium\/83475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/consortium"}],"about":[{"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/types\/consortium"}],"version-history":[{"count":4,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/consortium\/83475\/revisions"}],"predecessor-version":[{"id":84032,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/consortium\/83475\/revisions\/84032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/media\/151941"}],"wp:attachment":[{"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/media?parent=83475"}],"wp:term":[{"taxonomy":"consortium_region","embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/consortium_region?post=83475"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/tipologia?post=83475"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/provincia?post=83475"},{"taxonomy":"servizi_online","embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/servizi_online?post=83475"},{"taxonomy":"altro","embeddable":true,"href":"https:\/\/www.granapadano.it\/de-de\/wp-json\/wp\/v2\/altro?post=83475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}